{"id":41896,"date":"2020-01-08T11:55:56","date_gmt":"2020-01-08T17:55:56","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=41896"},"modified":"2020-01-08T11:55:56","modified_gmt":"2020-01-08T17:55:56","slug":"confia-amlo-que-senado-de-eu-apruebe-t-mec-esta-semana","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/confia-amlo-que-senado-de-eu-apruebe-t-mec-esta-semana\/","title":{"rendered":"Conf\u00eda AMLO que Senado de EU apruebe T-MEC esta semana"},"content":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador confi\u00f3 en que el Senado estadounidense apruebe el Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC) esta semana, pues el acuerdo comercial fue aprobado ayer por el Comit\u00e9 de Finanzas de la C\u00e1mara Alta y pas\u00f3 al pleno.<\/p>\n<p>\u00abVa a ser como era antes, aplanadora cuando pase a votaci\u00f3n, yo espero que ma\u00f1ana o pasado en el pleno la mayor\u00eda de los senadores de Estados Unidos va a votar por el tratado\u00bb, destac\u00f3 en su conferencia matutina.<\/p>\n<p>El mandatario dijo que la ratificaci\u00f3n del tratado en el Congreso estadounidense ser\u00eda positiva para el pa\u00eds, pues ser\u00e1 una se\u00f1al de seguridad y confianza. De aprobarse, ya solo restar\u00eda la votaci\u00f3n en el Congreso canadiense.<\/p>\n<p>El T-MEC ya fue aprobado por la C\u00e1mara de Representantes de Estados Unidos y, para completar su ratificaci\u00f3n, necesita el visto bueno del Senado, donde el l\u00edder de la mayor\u00eda republicana ha dicho que esperar\u00e1n hasta que se vote sobre el juicio pol\u00edtico de Donald Trump.<\/p>\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador confi\u00f3 en que el Senado estadounidense apruebe el Tratado entre M\u00e9xico, Estados Unidos y Canad\u00e1 (T-MEC) esta semana, pues el acuerdo comercial fue aprobado ayer por el Comit\u00e9 de Finanzas de la C\u00e1mara Alta y pas\u00f3 al pleno. \u00abVa a ser como era antes, aplanadora cuando pase a votaci\u00f3n,<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/confia-amlo-que-senado-de-eu-apruebe-t-mec-esta-semana\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":41897,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,40,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/01\/amlo-aprobara-manana-manana-jesus_0_42_958_596.jpeg?fit=1040%2C647&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-aTK","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/41896"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=41896"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/41896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/41897"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=41896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=41896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=41896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}