{"id":43148,"date":"2020-02-03T12:37:35","date_gmt":"2020-02-03T18:37:35","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=43148"},"modified":"2020-02-03T12:37:35","modified_gmt":"2020-02-03T18:37:35","slug":"adios-coronavirus-crean-lampara-capaz-de-eliminar-virus-y-bacterias-del-aire","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/adios-coronavirus-crean-lampara-capaz-de-eliminar-virus-y-bacterias-del-aire\/","title":{"rendered":"\u00a1Adi\u00f3s coronavirus! Crean l\u00e1mpara capaz de eliminar virus y bacterias del aire"},"content":{"rendered":"<p>No pudo llegar en mejor momento; en plena crisis del coronavirus, que se ha vuelto emergencia mundial decretada por la Organizaci\u00f3n Mundial de la Salud (OMS), la compa\u00f1\u00eda china Xiaomi ha creado una l\u00e1mpara capaz de eliminar virus y bacterias del aire en las casas.<\/p>\n<p>El coronavirus ha alertado a todo el mundo; esta nueva variaci\u00f3n del virus se est\u00e1 propagando r\u00e1pidamente alrededor del globo pues, actualmente, el padecimiento ha cobrado la vida de al menos 362 personas y van alrededor de 17 mil 205 contagiados.<\/p>\n<p>Ante la crisis, la compa\u00f1\u00eda Xiaomi, principalmente conocida por sus smartphones de alta calidad y precio accesible, ha desarrollado una l\u00e1mpara para el hogar, que podr\u00eda eliminar virus y bacterias del ambiente.<\/p>\n<p>La l\u00e1mpara que present\u00f3 la compa\u00f1\u00eda china cuenta con dos tubos UVC que se calientan y da\u00f1an el sistema reproductivo de bacterias portadoras de virus, desinfectando \u00e1reas cerradas como las habitaciones de las casas.<\/p>\n<p>El producto permite la entrada del aire en 360 grados y funciona de 20 a 30 metros cuadrados a la redonda. Adem\u00e1s, utiliza 35 watts de potencia y cuenta con 9 mil horas de vida \u00fatil.<\/p>\n<p>As\u00ed mismo, el prototipo tambi\u00e9n tiene la funci\u00f3n de alertar, mediante un dispositivo m\u00f3vil, si se detectan agentes v\u00edricos en ambiente donde se encuentre la l\u00e1mpara.<\/p>\n<p>La l\u00e1mpara que elimina virus y bacterias a\u00fan no ser\u00e1 lanzada al mercado y permanece como prototipo; sin embargo, se encuentra en proceso de financiaci\u00f3n a trav\u00e9s de la plataforma de recaudaci\u00f3n de fondos china, Youpin.<\/p>\n<p>Al momento se desconoce el precio de la misma, la fecha de lanzamiento y si solo estar\u00e1 disponible para China o para m\u00e1s pa\u00edses del mundo.<\/p>\n<p>Fuente: Agencias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No pudo llegar en mejor momento; en plena crisis del coronavirus, que se ha vuelto emergencia mundial decretada por la Organizaci\u00f3n Mundial de la Salud (OMS), la compa\u00f1\u00eda china Xiaomi ha creado una l\u00e1mpara capaz de eliminar virus y bacterias del aire en las casas. El coronavirus ha alertado a todo el mundo; esta nueva<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/adios-coronavirus-crean-lampara-capaz-de-eliminar-virus-y-bacterias-del-aire\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":43149,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,48,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/02\/lampara-elimina-virus-xiaomi-640x400.jpg?fit=1040%2C650&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-bdW","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/43148"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=43148"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/43148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/43149"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=43148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=43148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=43148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}