{"id":44061,"date":"2020-02-22T09:38:59","date_gmt":"2020-02-22T15:38:59","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=44061"},"modified":"2020-02-22T09:38:59","modified_gmt":"2020-02-22T15:38:59","slug":"se-mantendra-el-potencial-de-lluvias-en-el-sureste-de-mexico","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/se-mantendra-el-potencial-de-lluvias-en-el-sureste-de-mexico\/","title":{"rendered":"Se mantendr\u00e1 el potencial de lluvias en el sureste de M\u00e9xico"},"content":{"rendered":"<p>De acuerdo con el Servicio Meteorol\u00f3gico Nacional, el frente fr\u00edo n\u00famero 40 se extender\u00e1 sobre el Mar Caribe, dejando de afectar al pa\u00eds; sin embargo, su masa de aire fr\u00edo asociada mantendr\u00e1 las condiciones para nieblas y lluvias persistentes con acumulados fuertes en el sureste de M\u00e9xico, ambiente fr\u00edo en la Mesa del Norte y Mesa Central, adem\u00e1s de evento de &#8216;Norte&#8217; intenso en el Istmo y Golfo de Tehuantepec.<\/p>\n<p>Por otro lado, el frente fr\u00edo n\u00famero 41 ingresar\u00e1 y recorrer\u00e1 el noroeste del territorio nacional.<\/p>\n<p>Este interactuar\u00e1 con un v\u00f3rtice de n\u00facleo fr\u00edo en la atm\u00f3sfera superior, generando lluvias y vientos fuertes, descenso de temperatura, as\u00ed como ca\u00edda de aguanieve en zonas serranas de Baja California.<\/p>\n<p>Se prev\u00e9n intervalos de chubascos con lluvias puntuales fuertes en Sonora, Veracruz, Oaxaca, Tabasco y Chiapas. E intervalos de chubascos en Baja California y Chihuahua.<\/p>\n<p>As\u00ed como lluvias aisladas en Tamaulipas, San Luis Potos\u00ed, Puebla, Campeche, Yucat\u00e1n y Quintana Roo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con el Servicio Meteorol\u00f3gico Nacional, el frente fr\u00edo n\u00famero 40 se extender\u00e1 sobre el Mar Caribe, dejando de afectar al pa\u00eds; sin embargo, su masa de aire fr\u00edo asociada mantendr\u00e1 las condiciones para nieblas y lluvias persistentes con acumulados fuertes en el sureste de M\u00e9xico, ambiente fr\u00edo en la Mesa del Norte y<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/se-mantendra-el-potencial-de-lluvias-en-el-sureste-de-mexico\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":43956,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/02\/lluvias.jpg?fit=1040%2C645&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-bsF","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/44061"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=44061"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/44061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/43956"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=44061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=44061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=44061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}