{"id":44566,"date":"2020-03-04T12:36:32","date_gmt":"2020-03-04T18:36:32","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=44566"},"modified":"2020-03-04T12:36:32","modified_gmt":"2020-03-04T18:36:32","slug":"uif-solicita-a-ee-uu-informacion-sobre-vinculos-de-garcia-luna-con-grupo-delictivo","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/uif-solicita-a-ee-uu-informacion-sobre-vinculos-de-garcia-luna-con-grupo-delictivo\/","title":{"rendered":"UIF solicita a EE. UU. informaci\u00f3n sobre v\u00ednculos de Garc\u00eda Luna con grupo delictivo"},"content":{"rendered":"<p>El titular de la Unidad de Inteligencia Financiera (UIF) de la Secretar\u00eda de Hacienda, Santiago Nieto Castillo, dio a conocer que han solicitado informaci\u00f3n a Estados Unidos sobre los presuntos v\u00ednculos del exsecretrario de Seguridad, Genaro Garc\u00eda Luna, con un grupo delictivo, para que se incorpore a la investigaci\u00f3n que se realiza en M\u00e9xico.<\/p>\n<p>Durante conferencia de prensa ma\u00f1anera, el titular de la UIF detall\u00f3 que se investiga al exsecretario por corrupci\u00f3n, debido a que se detect\u00f3 que una de sus empresas de seguridad privada fue contratada por varias instancias del Gobierno mexicano.<\/p>\n<p>Dijo que Garc\u00eda Luna est\u00e1 denunciado en M\u00e9xico por corrupci\u00f3n pol\u00edtica y por esto han sido bloqueadas siete personas, icluyendo familiares y los due\u00f1os de una empresa.<\/p>\n<p>\u00abTen\u00eda una empresa que hab\u00eda sido contratada por varias instancias del Estado mexicano que el hab\u00eda adquirido en el a\u00f1o 2008, que era de tecnolog\u00eda israel\u00ed\u00bb, dijo.<\/p>\n<p>Fuente: Xeu Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de la Unidad de Inteligencia Financiera (UIF) de la Secretar\u00eda de Hacienda, Santiago Nieto Castillo, dio a conocer que han solicitado informaci\u00f3n a Estados Unidos sobre los presuntos v\u00ednculos del exsecretrario de Seguridad, Genaro Garc\u00eda Luna, con un grupo delictivo, para que se incorpore a la investigaci\u00f3n que se realiza en M\u00e9xico. Durante<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/uif-solicita-a-ee-uu-informacion-sobre-vinculos-de-garcia-luna-con-grupo-delictivo\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":44567,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,40,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/03\/1088166.jpg?fit=1040%2C693&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-bAO","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/44566"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=44566"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/44566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/44567"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=44566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=44566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=44566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}