{"id":45491,"date":"2020-03-26T10:21:43","date_gmt":"2020-03-26T16:21:43","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=45491"},"modified":"2020-03-26T10:21:43","modified_gmt":"2020-03-26T16:21:43","slug":"frente-frio-46-generara-lluvias-en-norte-y-noreste-de-mexico","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/frente-frio-46-generara-lluvias-en-norte-y-noreste-de-mexico\/","title":{"rendered":"Frente fr\u00edo 46 generar\u00e1 lluvias en norte y noreste de M\u00e9xico"},"content":{"rendered":"<p>De acuerdo con el Servicio Meteorol\u00f3gico Nacional, en el norte y noreste del pa\u00eds se prev\u00e9n lluvias y hasta ca\u00edda de nieve, debido a la presencia del frente fr\u00edo 46 y una vaguada polar.<\/p>\n<p>Se esperan intervalos de chubascos en Baja California, y lluvias aisladas en Sonora, Chihuahua, Coahuila y Chiapas.<\/p>\n<p>As\u00ed como ca\u00edda de nieve en la Sierra de San Pedro M\u00e1rtir, Baja California, y en el norte de Sonora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con el Servicio Meteorol\u00f3gico Nacional, en el norte y noreste del pa\u00eds se prev\u00e9n lluvias y hasta ca\u00edda de nieve, debido a la presencia del frente fr\u00edo 46 y una vaguada polar. Se esperan intervalos de chubascos en Baja California, y lluvias aisladas en Sonora, Chihuahua, Coahuila y Chiapas. As\u00ed como ca\u00edda de<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/frente-frio-46-generara-lluvias-en-norte-y-noreste-de-mexico\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":44006,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/02\/lluvias-cdmx1.jpg?fit=1040%2C667&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-bPJ","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/45491"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=45491"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/45491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/44006"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=45491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=45491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=45491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}