{"id":46054,"date":"2020-04-07T13:16:38","date_gmt":"2020-04-07T18:16:38","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=46054"},"modified":"2020-04-07T13:16:38","modified_gmt":"2020-04-07T18:16:38","slug":"hay-certeza-de-insumos-de-salud-para-enfrentar-covid-19-sanchez-cordero","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/hay-certeza-de-insumos-de-salud-para-enfrentar-covid-19-sanchez-cordero\/","title":{"rendered":"Hay certeza de insumos de salud para enfrentar Covid-19: S\u00e1nchez Cordero"},"content":{"rendered":"<p>La secretaria de Gobernaci\u00f3n, Olga S\u00e1nchez Cordero, asegur\u00f3 a gobernadores del norte del pa\u00eds que hay certeza sobre insumos de salud para enfrentar la pandemia del coronavirus Covid-19.<\/p>\n<p>En reuni\u00f3n virtual del gabinete de Seguridad con mandatarios estatales, coment\u00f3 a estos \u00faltimos que cuentan con el respaldo del Gobierno federal para enfrentar la emergencia nacional.<\/p>\n<p>En la videoconferencia se cont\u00f3 con la participaci\u00f3n de Marcelo Ebrard, secretario de Relaciones Exteriores; Jorge Alcocer Varela, secretario de Salud; Julio Scherer Ibarra, consejero Jur\u00eddico de Presidencia; Alfonso Durazo, secretario de Seguridad y Protecci\u00f3n Ciudadana; Luis Cresencio Sandoval, secretario de la Defensa Nacional y Jos\u00e9 Rafael Ojeda Dur\u00e1n, secretario de Marina.<\/p>\n<p>La Segob convoc\u00f3 a los gobernadores del norte para dar seguimiento al acuerdo por la gobernabilidad y unidad nacional, ante la contingencia por este virus.<\/p>\n<p>Los objetivos principales de este encuentro virtual fueron: continuar la aplicaci\u00f3n de las directrices del sector salud y tambi\u00e9n, conjuntamente, atender las demandas en materia econ\u00f3mica, pol\u00edtica y de seguridad entre el Gobierno federal, estados y municipios.<\/p>\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secretaria de Gobernaci\u00f3n, Olga S\u00e1nchez Cordero, asegur\u00f3 a gobernadores del norte del pa\u00eds que hay certeza sobre insumos de salud para enfrentar la pandemia del coronavirus Covid-19. En reuni\u00f3n virtual del gabinete de Seguridad con mandatarios estatales, coment\u00f3 a estos \u00faltimos que cuentan con el respaldo del Gobierno federal para enfrentar la emergencia nacional.<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/hay-certeza-de-insumos-de-salud-para-enfrentar-covid-19-sanchez-cordero\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":46055,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,40,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/04\/reunion-virtual-participo-canciller-marcelo_0_41_958_596_1024x637.jpg?fit=1024%2C637&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-bYO","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/46054"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=46054"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/46054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/46055"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=46054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=46054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=46054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}