{"id":46145,"date":"2020-04-09T09:45:41","date_gmt":"2020-04-09T14:45:41","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=46145"},"modified":"2020-04-09T09:45:41","modified_gmt":"2020-04-09T14:45:41","slug":"anuncia-amlo-acuerdo-con-china-para-abastecer-insumos-medicos-ante-coronavirus","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/anuncia-amlo-acuerdo-con-china-para-abastecer-insumos-medicos-ante-coronavirus\/","title":{"rendered":"Anuncia AMLO acuerdo con China para abastecer insumos m\u00e9dicos ante coronavirus"},"content":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador anunci\u00f3 que existe un acuerdo con China, para el abasto de insumos m\u00e9dicos para enfrentar la emergencia sanitaria por coronavirus en M\u00e9xico, el cual se lleva a cabo bajo la coordinaci\u00f3n de las secretar\u00edas de Relaciones Exteriores (SRE) y de Salud (SSa).<\/p>\n<p>El titular de la SRE, Marcelo Ebrard, asegur\u00f3 que se trabaja con China desde hace m\u00e1s de un mes para conseguir m\u00e1s material de protecci\u00f3n y monitoreo, as\u00ed como ventiladores, para atender a los mexicanos contagiados de Covid-19, \u00abiniciamos un despliegue internacional para reforzar el equipamiento de M\u00e9xico para hacer frente a la pandemia\u00bb.<\/p>\n<p>En conferencia matutina del presidente, detall\u00f3 que el 25 de marzo, a solicitud de la SRE, el Gobierno de China asign\u00f3 a la empresa Meheco como proveedora y el 29 de marzo se firm\u00f3 el contrato. Con lo que se logr\u00f3 que el 6 de abril se recogiera la primera mercanc\u00eda en Shangai de 725 mil guantes y 820 respiradores KN95, de la compa\u00f1\u00eda GuangZhou Powecom.<\/p>\n<p>En enero, la empresa norteamericana 3M realiz\u00f3 la equivalencia de est\u00e1ndares entre los respiradores, los Centros para la Prevenci\u00f3n y Control de Enfermedades de Estados Unidos hicieron lo mismo en febrero, mientras que la Cofepris los aval\u00f3 el 7 de abril.<\/p>\n<p>\u00abDesde febrero establecieron la equivalencia entre los mismos est\u00e1ndares; nuestro proveedor de china cumple con la equivalencia de KN95\u00bb, coment\u00f3. <\/p>\n<p>Ebrard inform\u00f3 que ma\u00f1ana por la noche llegar\u00e1 otro vuelo desde China que transportar\u00e1 mascarillas o cubrebocas y caretas.<\/p>\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador anunci\u00f3 que existe un acuerdo con China, para el abasto de insumos m\u00e9dicos para enfrentar la emergencia sanitaria por coronavirus en M\u00e9xico, el cual se lleva a cabo bajo la coordinaci\u00f3n de las secretar\u00edas de Relaciones Exteriores (SRE) y de Salud (SSa). El titular de la SRE, Marcelo Ebrard,<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/anuncia-amlo-acuerdo-con-china-para-abastecer-insumos-medicos-ante-coronavirus\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":46146,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/04\/lopez-obrador-agradecio-sigan-medidas_0_21_958_596.jpeg?fit=1040%2C647&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-c0h","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/46145"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=46145"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/46145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/46146"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=46145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=46145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=46145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}