{"id":46454,"date":"2020-04-15T15:28:05","date_gmt":"2020-04-15T20:28:05","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=46454"},"modified":"2020-04-15T15:28:05","modified_gmt":"2020-04-15T20:28:05","slug":"pide-fgr-homologar-penalizacion-del-feminicidio","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/pide-fgr-homologar-penalizacion-del-feminicidio\/","title":{"rendered":"Pide FGR homologar penalizaci\u00f3n del feminicidio"},"content":{"rendered":"<p>El fiscal general de la Rep\u00fablica, Alejandro Gertz Manero, llam\u00f3 a hacer un esfuerzo de todos los sectores para homologar la penalizaci\u00f3n del feminicidio en todo el pa\u00eds.<\/p>\n<p>Al participar en el Foro Nacional virtual &#8216;El combate al feminicidio, a 8 a\u00f1os de su incorporaci\u00f3n en el Sistema de Justicia: experiencias y desaf\u00edos&#8217;, organizado por la C\u00e1mara de Diputados, el funcionario destac\u00f3 la necesidad de homologar la penalizaci\u00f3n de ese delito en todas las legislaturas locales.<\/p>\n<p>\u201cDonde tenemos el problema, subray\u00f3, es en tratar de homologar un tipo penal de orden com\u00fan que pueda ser aplicado y recibido por las legislaturas locales, para que hagamos un esfuerzo de homologaci\u00f3n a nivel de todo el pa\u00eds, tomando en cuenta algo, que es fundamental: \u00bfcu\u00e1les son los requerimientos que tiene ese delito y las capacidades que tienen quienes lo combaten y quienes lo previenen?\u201d, se\u00f1al\u00f3.<\/p>\n<p>Gertz Manero dio todo el respaldo de la Fiscal\u00eda General de la Rep\u00fablica, as\u00ed como su voluntad y colaboraci\u00f3n de la dependencia; sin embargo, aclar\u00f3 que se hace la propuesta porque el delito de feminicidio no es fuero federal.<\/p>\n<p>\u201cEn este trabajo nosotros queremos reiterar toda la voluntad y la colaboraci\u00f3n de nuestra instituci\u00f3n que, como ustedes tambi\u00e9n lo saben, estos delitos no son del fuero federal\u201d, precis\u00f3.<\/p>\n<p>Agreg\u00f3 que si se trabaja de manera coordinada y se establecen con precisi\u00f3n los aspectos a tomarse en cuenta para la homologaci\u00f3n de la penalizaci\u00f3n del feminicidio en todo el pa\u00eds, se lo lograr\u00e1n resultados satisfactorios.<\/p>\n<p>\u201cLlevamos ya varios meses trabajando con un ideal com\u00fan: c\u00f3mo vamos a encontrar la mejor manera de defender a las mujeres frente a este delito tan grave que tanto nos acongoja. Creo que hemos hecho, cada uno de nosotros, aportaciones que deben de unirse para que demos un resultado general que sea en bien de las v\u00edctimas\u201d, solicit\u00f3.<\/p>\n<p>Fuente: Notimex<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fiscal general de la Rep\u00fablica, Alejandro Gertz Manero, llam\u00f3 a hacer un esfuerzo de todos los sectores para homologar la penalizaci\u00f3n del feminicidio en todo el pa\u00eds. Al participar en el Foro Nacional virtual &#8216;El combate al feminicidio, a 8 a\u00f1os de su incorporaci\u00f3n en el Sistema de Justicia: experiencias y desaf\u00edos&#8217;, organizado por<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/pide-fgr-homologar-penalizacion-del-feminicidio\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":46455,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/04\/FGR.jpg?fit=1040%2C693&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-c5g","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/46454"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=46454"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/46454\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/46455"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=46454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=46454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=46454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}