{"id":48751,"date":"2020-06-04T19:46:35","date_gmt":"2020-06-05T00:46:35","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=48751"},"modified":"2020-06-04T19:46:38","modified_gmt":"2020-06-05T00:46:38","slug":"claman-empresarios-a-amlo-claridad-en-inversion-publica-para-evitar-desastre-economico","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/claman-empresarios-a-amlo-claridad-en-inversion-publica-para-evitar-desastre-economico\/","title":{"rendered":"Claman empresarios a AMLO claridad en inversi\u00f3n p\u00fablica para evitar desastre econ\u00f3mico"},"content":{"rendered":"\n<p>El Consejo Coordinador Empresarial (CCE) del sur de Veracruz resumi\u00f3 en cuatro puntos su postura, ante la visita del presidente Andr\u00e9s Manuel L\u00f3pez Obrador que estar\u00e1 en tres municipios de esta regi\u00f3n.<\/p>\n\n\n\n<p>Las c\u00e1maras adheridas al CCE coincidieron en afirmar que existe inter\u00e9s en seguir la gira de L\u00f3pez Obrador, en vista que se trata de una agenda tem\u00e1tica relacionada con el desarrollo econ\u00f3mico de esta zona.<\/p>\n\n\n\n<p>El CCE enfatiz\u00f3 que desde hace varios a\u00f1os el sur de Veracruz padece la falta de inversiones en infraestructura, ausencia de programas de fomento a la inversi\u00f3n para las cadenas de producci\u00f3n y servicios, p\u00e9rdida galopante de empleos y, como efecto indeseable de todo lo anterior, una creciente escalada delictiva y de inseguridad en esta regi\u00f3n.<\/p>\n\n\n\n<p>Ante tal situaci\u00f3n, desde luego agravada por la pandemia de Covid 19 que afecta severamente a municipios del sur de Veracruz, las c\u00e1maras empresariales urgieron a que la visita presidencial sirva para definir las medidas, acciones y programas de inversi\u00f3n previstas para esta zona tan lastimada.<\/p>\n\n\n\n<p>En un documento elaborado por el CCE se resumen cuatro puntos que deben atenderse a la brevedad para darle certidumbre al panorama econ\u00f3mico de la regi\u00f3n:<\/p>\n\n\n\n<p>1.- Los proyectos de refinaci\u00f3n anunciados en la v\u00edspera con la producci\u00f3n de combustibles en la l\u00ednea de arom\u00e1ticos del Complejo Petroqu\u00edmico Cangrejera, debe determinar sus alcances inmediatos con proyectos ejecutivos y licitaciones de corto plazo, con reglas claras e incluyentes que permitan la participaci\u00f3n de empresas de la regi\u00f3n sur, que dicho sea de paso, cuentan con el expertise y la trayectoria para asumir con profesionalismo y solvencia t\u00e9cnica los proyectos que eventualmente se ejecuten en este sector.<\/p>\n\n\n\n<p>2.- En el sector energ\u00e9tico hemos reiterado en m\u00faltiples foros la baja sostenida en la producci\u00f3n de insumos del sector petroqu\u00edmico como es el caso de la cadena etano-etileno y derivados como \u00f3xido de etileno, paraxileno as\u00ed como la l\u00ednea de gas-amoniaco que integra una de las cadenas de valor m\u00e1s importante para el pa\u00eds y particularmente la regi\u00f3n sur del Veracruz, en donde se establece el principal conglomerado petroqu\u00edmico del pa\u00eds.<\/p>\n\n\n\n<p>3.- Hemos seguido con mucha atenci\u00f3n los proyectos de desarrollo de la franja entre Veracruz y Oaxaca, enmarcados en el nuevo plan Corredor Interoce\u00e1nico del Istmo de Tehuantepec (CIIT) que como sabemos constituye uno de los ejes m\u00e1s importantes de la pol\u00edtica de desarrollo econ\u00f3mico del Gobierno Federal. No obstante, es poca la informaci\u00f3n que tenemos del aterrizaje de corto plazo de los m\u00faltiples proyectos en cartera del CIIT, no hay o probablemente no estemos enterados de las licitaciones en todos los frentes de obra tanto portuaria, aereoportuaria, carretera, ferroviaria, de telecomunicaciones y de servicios complementarios que integran este nuevo programa de desarrollo para la zona del istmo.<\/p>\n\n\n\n<p>4.- Es urgente que el Gobierno Federal a trav\u00e9s de sus organismos subsidiarios as\u00ed como el Gobierno del estado de Veracruz asuman la gravedad que nos representa para muchas empresas los millonarios pasivos por prestaci\u00f3n de servicios el sector p\u00fablico que no han sido pagados y que han provocado la insolvencia y en peores casos la quiebra de muchas micros, peque\u00f1as y medianas empresas de esta regi\u00f3n. Hablamos particularmente de los adeudos que tiene Pemex con proveedores y contratistas de la regi\u00f3n que desde hace muchos meses est\u00e1n en un constante peregrinar para que les sean cubiertos sus servicios ya prestados. Es en verdad lamentable que no se obtenga respuesta de los adeudos que adem\u00e1s implicaron en muchos casos el apalancamiento financiero de empresas que hoy adem\u00e1s de no tener su pago enfrentan dram\u00e1ticamente las deudas con bancos.<\/p>\n\n\n\n<p>El sector empresarial de la regi\u00f3n se declar\u00f3 francamente preocupado por la situaci\u00f3n que vive nuestra regi\u00f3n que viene arrastrando problemas econ\u00f3micos desde hace muchos a\u00f1os y que hoy se ha complicado a\u00fan m\u00e1s por la situaci\u00f3n sanitaria del Covid 19 \u201c Que nos oblig\u00f3 a replegar actividades y que en la espiral nos dej\u00f3 sin mercado, sin clientes y sin horizonte econ\u00f3mico\u201d dice un documento elaborado por el CCE.<\/p>\n\n\n\n<p>\u201cHemos tratado de sostener empleos y cumplir con nuestras obligaciones fiscales pero la situaci\u00f3n se torna verdaderamente grave por lo que es urgente inyectar recursos a la actividad productiva de la regi\u00f3n para lograr ubicar una l\u00ednea de partida para alcanzar un punto de equilibrio de mediano plazo en esta zona que usted conoce perfectamente y que sabemos es de su especial aprecio\u201d Concluye.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Destacamos El Consejo Coordinador Empresarial (#CCE) del sur de #Veracruz resumi\u00f3 en cuatro puntos su postura, ante la visita del presidente #Andr\u00e9sManuelL\u00f3pezObrador que estar\u00e1 en tres municipios de esta regi\u00f3n.<\/p>\n","protected":false},"author":5,"featured_media":48752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/06\/a901f8cc-7967-49cb-b6b9-c257640656c1.jpg?fit=1265%2C703&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-cGj","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/48751"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=48751"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/48751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/48752"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=48751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=48751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=48751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}