{"id":49425,"date":"2020-06-18T16:07:47","date_gmt":"2020-06-18T21:07:47","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=49425"},"modified":"2020-06-18T16:07:52","modified_gmt":"2020-06-18T21:07:52","slug":"ee-uu-sanciona-a-libre-abordo-y-otra-empresa-mexicana-por-vinculos-con-venezuela","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/ee-uu-sanciona-a-libre-abordo-y-otra-empresa-mexicana-por-vinculos-con-venezuela\/","title":{"rendered":"EE. UU. sanciona a Libre Abordo y otra empresa mexicana por v\u00ednculos con Venezuela"},"content":{"rendered":"\n<p>Estados Unidos puso en su lista negra a la\u00a0empresa mexicana Libre Abordo y a una firma relacionada, a las que acus\u00f3 de ayudar a Venezuela a evadir sus sanciones, en la primera medida formal del Departamento del Tesoro contra compa\u00f1\u00edas de M\u00e9xico involucradas en el comercio de\u00a0petr\u00f3leo venezolano.<\/p>\n\n\n\n<p>El\u00a0Departamento del Tesoro\u00a0dijo en un comunicado que impuso sanciones a tres individuos, ocho entidades extranjeras y dos embarcaciones por actividades relacionadas con una\u00a0red que intentaba eludir las sanciones estadounidenses a Venezuela, con las que Washington busca presionar a Nicol\u00e1s Maduro.<\/p>\n\n\n\n<p>En la\u00a0lista negra\u00a0figuraban la empresa mexicana Libre Abordo y Schlager Business Group, as\u00ed como sus copropietarios, la mexicana Olga Mar\u00eda Zepeda Esparza y su madre, Ver\u00f3nica Esparza Garc\u00eda.<\/p>\n\n\n\n<p>Tambi\u00e9n apunt\u00f3 al mexicano Joaqu\u00edn Leal Jim\u00e9nez, a quien\u00a0acus\u00f3 de haber trabajado con Alex Saab\u00a0-recientemente detenido en Cabo Verde-, Libre Abordo y Schlager Business Group, para negociar la reventa de millones de barriles de\u00a0crudo venezolano.<\/p>\n\n\n\n<p>\u00abEl ileg\u00edtimo r\u00e9gimen de Maduro cre\u00f3 una red secreta para evadir las sanciones que el Tesoro ha expuesto ahora\u00bb, dijo el subsecretario del Tesoro Justin Muzinich en el comunicado. \u00abEstados Unidos continuar\u00e1 persiguiendo sin descanso a los evasores de sanciones\u00bb, a\u00f1adi\u00f3.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Libre Abordo y el petr\u00f3leo de Venezuela<\/strong><\/h2>\n\n\n\n<p>Libre Abordo y Schlager Business Group comenzaron a recibir crudo venezolano para su reventa en los mercados asi\u00e1ticos\u00a0a finales del a\u00f1o pasado, despu\u00e9s de firmar dos contratos con el gobierno de Maduro a mediados de 2019.<\/p>\n\n\n\n<p>El acuerdo se enmarc\u00f3 en un\u00a0pacto de petr\u00f3leo por alimentos exento de las sanciones de Estados Unidos. Las empresas mexicanas pretend\u00edan suministrar a Venezuela 210 mil toneladas de ma\u00edz como parte del acuerdo.<\/p>\n\n\n\n<p>Desde que comenzaron los env\u00edos de petr\u00f3leo, Libre Abordo y Schlager recibieron unos 30 millones de barriles de petr\u00f3leo venezolano, seg\u00fan los documentos de exportaci\u00f3n de PDVSA.<\/p>\n\n\n\n<p>A pesar de que el petr\u00f3leo se cambi\u00f3 por unos 500 camiones cisterna, nunca se suministraron alimentos, ya que los baj\u00edsimos precios del crudo afectaron el calendario de entrega acordado originalmente, seg\u00fan las empresas.<\/p>\n\n\n\n<p><em>Reuters<\/em>\u00a0inform\u00f3 el mes pasado, citando a cuatro personas familiarizadas con el asunto, que el FBI estaba investigando a varias compa\u00f1\u00edas mexicanas y europeas supuestamente involucradas en el\u00a0comercio de petr\u00f3leo venezolano, reuniendo informaci\u00f3n para una investigaci\u00f3n del Departamento del Tesoro para la posible imposici\u00f3n de sanciones.<\/p>\n\n\n\n<p>Fuente: Agencias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Destacamos #EstadosUnidos puso en su lista negra a la empresa mexicana #LibreAbordo y a una firma relacionada, a las que acus\u00f3 de ayudar a #Venezuela a evadir sus sanciones; estar\u00edan involucradas en el comercio de #petr\u00f3leo venezolano.<\/p>\n","protected":false},"author":5,"featured_media":49426,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,40,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/06\/consumo-petroleo-alcanzara-pico-maximo_0_26_978_607.jpg?fit=958%2C596&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-cRb","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/49425"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=49425"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/49425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/49426"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=49425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=49425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=49425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}