{"id":50470,"date":"2020-07-08T21:03:35","date_gmt":"2020-07-09T02:03:35","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=50470"},"modified":"2020-07-08T21:03:38","modified_gmt":"2020-07-09T02:03:38","slug":"atenderan-28-colonias-en-primera-fase-de-jornadas-de-fumigacion","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/atenderan-28-colonias-en-primera-fase-de-jornadas-de-fumigacion\/","title":{"rendered":"Atender\u00e1n 28 colonias en primera fase de jornadas de fumigaci\u00f3n"},"content":{"rendered":"\n<p>Con el objetivo de que colonias de Coatzacoalcos, Villa Allende y Mundo Nuevo est\u00e9n libres de criaderos de mosquitos transmisores de enfermedades como el dengue, zika y chikungunya, la Direcci\u00f3n de Programas Sociales, en coordinaci\u00f3n con el Departamento de Vectores de la Jurisdicci\u00f3n Sanitaria N\u00famero 11 atender\u00e1 en una primera fase a 28 centros poblacionales.<\/p>\n\n\n\n<p>El d\u00eda de hoy, se realiz\u00f3 la segunda jornada en la colonia Villas de la Rivera, se prosigui\u00f3 en la Nueva Obrera y posteriormente, H\u00e9roes de Nacozari.<\/p>\n\n\n\n<p>Es importante resaltar que, con un d\u00eda de anticipaci\u00f3n se perifonea en las calles de los sectores que se visitar\u00e1, inform\u00f3 Sandra Collins Coronel, titular de la Direcci\u00f3n de Programas Sociales.<\/p>\n\n\n\n<p>Agreg\u00f3 que, durante esa actividad, tambi\u00e9n se exhorta a los due\u00f1os de las casas a que permitan que el personal de vectores pueda ingresar a su hogar para fumigar y colocar abatizante en los dep\u00f3sitos de agua e invitarlos a que todos los recipientes que utilicen para almacenar l\u00edquidos est\u00e9n perfectamente tapados.<\/p>\n\n\n\n<p>Manifest\u00f3 que las colonias que est\u00e1n asentadas en zona pantanosa, representan un foco rojo por el alto grado de probabilidades de que se generen criaderos de mosquitos, es por ello que colaboradores de la Jurisdicci\u00f3n les indica a los habitantes sobre c\u00f3mo prevenir la proliferaci\u00f3n de estos insectos.<\/p>\n\n\n\n<p>La funcionaria, precis\u00f3 que el pr\u00f3ximo viernes se acudir\u00e1 a la colonia Fidel Herrera y se planea terminar el mes de julio, el d\u00eda 27, atendiendo a la Congregaci\u00f3n de Mundo Nuevo, no sin antes pasar por Villa Allende.<\/p>\n\n\n\n<p>Los trabajadores del \u00e1rea de Vectores est\u00e1n debidamente acreditados y uniformados, adem\u00e1s que siempre son acompa\u00f1ados de alg\u00fan representante de la Direcci\u00f3n de Programas Sociales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Destacamos Con el objetivo de que colonias de #Coatzacoalcos, #VillaAllende y #MundoNuevo est\u00e9n libres de criaderos de #mosquitos transmisores del #dengue, #zika y #chikungunya, autoridades municipales atender\u00e1n en una primera fase a 28 centros poblacionales.<\/p>\n","protected":false},"author":5,"featured_media":50471,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/07\/380dd231-641e-4e87-b42b-e8339853709c.jpg?fit=1040%2C693&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-d82","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/50470"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=50470"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/50470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/50471"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=50470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=50470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=50470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}