{"id":50560,"date":"2020-07-10T13:21:11","date_gmt":"2020-07-10T18:21:11","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=50560"},"modified":"2020-07-10T13:21:15","modified_gmt":"2020-07-10T18:21:15","slug":"sancionarian-a-quienes-no-usen-cubrebocas-en-xalapa","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/sancionarian-a-quienes-no-usen-cubrebocas-en-xalapa\/","title":{"rendered":"Sancionar\u00edan a quienes no usen cubrebocas en Xalapa"},"content":{"rendered":"\n<p>El Cabildo de Xalapa, Veracruz,\u00a0analiza aprobar sanciones para quienes no usen cubrebocas en la v\u00eda p\u00fablica, con el fin de frenar los contagios de Covid-19.<\/p>\n\n\n\n<p>\u00abEs una decisi\u00f3n que est\u00e1 por tomarse, debe tomarse porque en Xalapa se han incrementado considerablemente los decesos y el n\u00famero de contagios por Covid-19, eso ha obligado al Ayuntamiento a otras medidas, pero el Cabildo, los ediles tendr\u00e1n que tomar esta determinaci\u00f3n\u00bb, se\u00f1al\u00f3 el director de Gobernaci\u00f3n, Juan Vergel Pacheco.<\/p>\n\n\n\n<p>Dijo que se busca que en sitios concurridos sea obligatorio el uso de las mascarillas, para frenar los contagios.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que est\u00e1n revisando los detalles del monto de la multa, el respaldo jur\u00eddico y la designaci\u00f3n de \u00e1reas responsables de hacer cumplir la disposici\u00f3n.<\/p>\n\n\n\n<p>De acuerdo con el funcionario, las \u00e1reas de Salud, Comercio y Movilidad podr\u00edan ser las responsables de vigilar el cumplimiento.<\/p>\n\n\n\n<p>Destac\u00f3 que en los comercios ya es obligatorio usar el cubrebocas y gran parte lo hace, pero entre la ciudadan\u00eda a\u00fan no se establece.<\/p>\n\n\n\n<p>Fuente: Xeu Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>#Atento El Cabildo de #Xalapa, #Veracruz, analiza aprobar #sanciones para quienes no usen #cubrebocas en la v\u00eda p\u00fablica, con el fin de frenar los #contagios de #Covid19.<\/p>\n","protected":false},"author":5,"featured_media":50561,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/07\/cubrebocas.jpg?fit=1040%2C662&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-d9u","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/50560"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=50560"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/50560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/50561"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=50560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=50560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=50560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}