{"id":51174,"date":"2020-07-23T15:17:30","date_gmt":"2020-07-23T20:17:30","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=51174"},"modified":"2020-07-23T15:17:36","modified_gmt":"2020-07-23T20:17:36","slug":"asesinan-a-dos-policias-en-misantla","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/asesinan-a-dos-policias-en-misantla\/","title":{"rendered":"Asesinan a dos polic\u00edas en Misantla"},"content":{"rendered":"\n<p>Dos polic\u00edas fueron hallados sin vida este jueves, en la entrada del municipio de Misantla, Veracruz; las v\u00edctimas presentaban impactos de arma de fuego.<\/p>\n\n\n\n<p>De acuerdo con los reportes, los elementos habr\u00edan sido privados de la vida la madrugada de este jueves en el arco de bienvenida de Misantla.<\/p>\n\n\n\n<p>Fueron habitantes de la zona quienes encontraron los dos cuerpos, por lo que dieron aviso a las autoridades para realizar las diligencias del caso.<\/p>\n\n\n\n<p>Cabe mencionar que hasta el momento se desconoce la identidad de las v\u00edctimas.<\/p>\n\n\n\n<p>Fuente: Xeu Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos polic\u00edas fueron hallados sin vida este jueves, en la entrada del municipio de Misantla, Veracruz; las v\u00edctimas presentaban impactos de arma de fuego. De acuerdo con los reportes, los elementos habr\u00edan sido privados de la vida la madrugada de este jueves en el arco de bienvenida de Misantla. Fueron habitantes de la zona quienes<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/asesinan-a-dos-policias-en-misantla\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":51175,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/07\/acordonamiento.jpg?fit=1024%2C616&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-djo","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51174"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=51174"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/51175"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=51174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=51174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=51174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}