{"id":51319,"date":"2020-07-27T11:07:32","date_gmt":"2020-07-27T16:07:32","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=51319"},"modified":"2020-07-27T11:07:38","modified_gmt":"2020-07-27T16:07:38","slug":"protestan-jubilados-de-mexicana-en-mananera-de-amlo","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/protestan-jubilados-de-mexicana-en-mananera-de-amlo\/","title":{"rendered":"Protestan jubilados de Mexicana en ma\u00f1anera de AMLO"},"content":{"rendered":"\n<p>Jubilados de Mexicana de Aviaci\u00f3n protestaron a las afueras del exhangar presidencial, donde se realiz\u00f3 la conferencia ma\u00f1anera del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, la ma\u00f1ana de este lunes.<\/p>\n\n\n\n<p>Exigen el pago de pensiones y que se respete el laudo que ya caus\u00f3 estado, ocasion\u00e1ndoles dos embargos.<\/p>\n\n\n\n<p>Piden apoyo al presidente porque la mayor\u00eda de los extrabajadores consiguieron empleos, pero ellos rebasan los 60 a\u00f1os y no consiguen trabajo en ning\u00fan lado.<\/p>\n\n\n\n<p>Fuente: la Jornada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jubilados de Mexicana de Aviaci\u00f3n protestaron a las afueras del exhangar presidencial, donde se realiz\u00f3 la conferencia ma\u00f1anera del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, la ma\u00f1ana de este lunes. Exigen el pago de pensiones y que se respete el laudo que ya caus\u00f3 estado, ocasion\u00e1ndoles dos embargos. Piden apoyo al presidente porque la mayor\u00eda de<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/protestan-jubilados-de-mexicana-en-mananera-de-amlo\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":51320,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/07\/1113291.jpg?fit=1024%2C612&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dlJ","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51319"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=51319"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/51320"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=51319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=51319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=51319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}