{"id":51416,"date":"2020-07-28T18:37:51","date_gmt":"2020-07-28T23:37:51","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=51416"},"modified":"2020-07-28T18:37:58","modified_gmt":"2020-07-28T23:37:58","slug":"proponen-lineamientos-para-nombramiento-de-la-titular-de-ivm","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/proponen-lineamientos-para-nombramiento-de-la-titular-de-ivm\/","title":{"rendered":"Proponen lineamientos para nombramiento de la titular de IVM"},"content":{"rendered":"\n<p>La diputada Mar\u00eda Esther L\u00f3pez Callejas present\u00f3 ante el pleno de la LXV Legislatura una iniciativa con Proyecto de Decreto que reforma, adiciona y deroga diversas disposiciones de la Ley que crea el Instituto Veracruzano de las Mujeres (IVM), con el que se pretende homologar la figura del nombramiento de la directora del organismo, desplazando esas facultades a la Junta de Gobierno, garantizando que las pol\u00edticas p\u00fablicas se desarrollen en un contexto institucional.<\/p>\n\n\n\n<p>En este sentido, es necesario homologar los procedimientos administrativos, trayendo las figuras de la ley que rige al propio Instituto Nacional de las Mujeres a las locales optimizando recursos y concentrando las propias instituciones en la forma m\u00e1s eficiente de ejecuci\u00f3n, como lo es la obtenci\u00f3n de decisiones, tanto en la Junta de Gobierno como en la conformaci\u00f3n de los Consejos auxiliares.<\/p>\n\n\n\n<p>Asimismo, la iniciativa propone la incorporaci\u00f3n a la Junta de Gobierno de la o el titular de la Secretar\u00eda de Gobierno para que tenga voz y voto dentro del m\u00e1ximo \u00f3rgano de decisi\u00f3n.<\/p>\n\n\n\n<p>Para la elecci\u00f3n de la titular del IVM este deber\u00e1 alcanzar por acuerdo de las tres quintas partes de la totalidad de sus integrantes de la Junta de Gobierno, de no ser as\u00ed, una terna se someter\u00e1 a consideraci\u00f3n de la o el titular del Poder Ejecutivo, quien designar\u00e1 a la titular del IVM. Ante la ausencia de la titular, ser\u00e1 la Secretaria Ejecutiva del Instituto asumir\u00e1 las funciones de Directora, como Encargada de Despacho.<\/p>\n\n\n\n<p>En el mismo sentido, destaca la propuesta, el Consejo Consultivo estar\u00e1 integrado por un n\u00famero no menor de cinco ni mayor a ocho mujeres que propongan las diferentes organizaciones sociales, asociaciones civiles, instituciones acad\u00e9micas, campesinas e ind\u00edgenas con experiencia o formaci\u00f3n en el \u00e1mbito de la igualdad de g\u00e9nero y derechos humanos de las mujeres.<\/p>\n\n\n\n<p>Adem\u00e1s, faculta al Consejo Consultivo a colaborar con el IVM en el acompa\u00f1amiento en las gestiones que requieran mayor impulso y promoci\u00f3n a las acciones para la igualdad de oportunidades y no discriminaci\u00f3n contra las mujeres.<\/p>\n\n\n\n<p>Para su estudio y dictamen, la iniciativa fue turnada a la Comisi\u00f3n Permanente para la Igualdad de G\u00e9nero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La diputada Mar\u00eda Esther L\u00f3pez Callejas present\u00f3 ante el pleno de la LXV Legislatura una iniciativa con Proyecto de Decreto que reforma, adiciona y deroga diversas disposiciones de la Ley que crea el Instituto Veracruzano de las Mujeres (IVM), con el que se pretende homologar la figura del nombramiento de la directora del organismo, desplazando<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/proponen-lineamientos-para-nombramiento-de-la-titular-de-ivm\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":51432,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/07\/10.jpg?fit=1040%2C780&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dni","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51416"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=51416"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/51432"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=51416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=51416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=51416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}