{"id":51821,"date":"2020-08-05T12:55:12","date_gmt":"2020-08-05T17:55:12","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=51821"},"modified":"2020-08-05T12:55:16","modified_gmt":"2020-08-05T17:55:16","slug":"ayuntamiento-de-tapalpa-jalisco-implementa-toque-de-queda-por-covid-19","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/ayuntamiento-de-tapalpa-jalisco-implementa-toque-de-queda-por-covid-19\/","title":{"rendered":"Ayuntamiento de Tapalpa, Jalisco, implementa toque de queda por Covid-19"},"content":{"rendered":"\n<p>El Ayuntamiento de Tapalpa, Jalisco, impuso un toque de queda en el municipio debido a la pandemia de Covid-19, por lo que habr\u00e1 sanciones para todas aquellas personas que est\u00e9n en la calle a partir de las nueve de la noche.<\/p>\n\n\n\n<p>La alcaldesa, Luz Elvira Manzano Ochoa, mencion\u00f3 que la decisi\u00f3n se tom\u00f3 a partir del incremento de contagios de Covid-19.<\/p>\n\n\n\n<p>\u201cAdicional a esto, se reforzar\u00e1n las medidas de sanidad que se han venido implementando en el municipio, como son el uso de cubrebocas de manera obligatoria, el uso de gel, lavado de manos y la sana distancia en espacios p\u00fablicos, establecimientos, restaurantes en el \u00e1rea hotelera\u201d, dijo.<\/p>\n\n\n\n<p>No se inform\u00f3 si se instalar\u00edan filtros en los ingresos carreteros para restringir el paso de visitantes.<\/p>\n\n\n\n<p>El primer contagio notificado de Covid-19 en Tapalpa se report\u00f3 el pasado 23 de junio y actualmente documenta 11 contagios. De momento no hay decesos.<\/p>\n\n\n\n<p>Fuente: Notisistema<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ayuntamiento de Tapalpa, Jalisco, impuso un toque de queda en el municipio debido a la pandemia de Covid-19, por lo que habr\u00e1 sanciones para todas aquellas personas que est\u00e9n en la calle a partir de las nueve de la noche. La alcaldesa, Luz Elvira Manzano Ochoa, mencion\u00f3 que la decisi\u00f3n se tom\u00f3 a partir<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/ayuntamiento-de-tapalpa-jalisco-implementa-toque-de-queda-por-covid-19\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":51822,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/08\/Tapalpa-1-610x389-1.jpg?fit=1040%2C663&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dtP","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51821"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=51821"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/51821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/51822"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=51821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=51821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=51821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}