{"id":52398,"date":"2020-08-17T11:30:11","date_gmt":"2020-08-17T16:30:11","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=52398"},"modified":"2020-08-17T11:30:16","modified_gmt":"2020-08-17T16:30:16","slug":"conductores-de-television-no-daran-clases-seran-los-mejores-maestros-de-mexico-lopez-obrador","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/conductores-de-television-no-daran-clases-seran-los-mejores-maestros-de-mexico-lopez-obrador\/","title":{"rendered":"Conductores de televisi\u00f3n no dar\u00e1n clases, ser\u00e1n los mejores maestros de M\u00e9xico: L\u00f3pez Obrador"},"content":{"rendered":"\n<p>Ser\u00e1n los\u00a0 mejores maestros, y no los conductores de televisi\u00f3n, quienes den clases en educaci\u00f3n en l\u00ednea, asegur\u00f3 el presidente Andr\u00e9s Manuel L\u00f3pez Obrador ante el inicio del ciclo escolar el pr\u00f3ximo\u00a024 de agosto con el programa &#8216;Aprende en Casa&#8217;.<\/p>\n\n\n\n<p>\u00abAcerca de los maestros, no son conductores de televisi\u00f3n porque ellos no podr\u00edan hacerlo, porque tienen otras ocupaciones; ademas, dar clases es algo especializado, no es como ser presidente o ser periodista, se requiere ser maestro o maestra\u00bb, dijo en conferencia de prensa ma\u00f1anera.<\/p>\n\n\n\n<p>En este sentido, cuestion\u00f3: \u00ab\u00bfEntonces qui\u00e9nes van a dar clases? Maestras y maestros; eso s\u00ed, muy buenos, no siempre, pero de los mejores maestros de literatura de M\u00e9xico van a estar ah\u00ed, se les va a invitar, de f\u00edsica, de biolog\u00eda, de matem\u00e1ticas\u00bb.<\/p>\n\n\n\n<p>Fuente: Xeu Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1n los\u00a0 mejores maestros, y no los conductores de televisi\u00f3n, quienes den clases en educaci\u00f3n en l\u00ednea, asegur\u00f3 el presidente Andr\u00e9s Manuel L\u00f3pez Obrador ante el inicio del ciclo escolar el pr\u00f3ximo\u00a024 de agosto con el programa &#8216;Aprende en Casa&#8217;. \u00abAcerca de los maestros, no son conductores de televisi\u00f3n porque ellos no podr\u00edan hacerlo, porque<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/conductores-de-television-no-daran-clases-seran-los-mejores-maestros-de-mexico-lopez-obrador\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":52399,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,40,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/08\/Clases.jpg?fit=1040%2C587&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dD8","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52398"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=52398"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/52399"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=52398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=52398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=52398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}