{"id":52485,"date":"2020-08-18T14:35:14","date_gmt":"2020-08-18T19:35:14","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=52485"},"modified":"2020-08-18T14:35:20","modified_gmt":"2020-08-18T19:35:20","slug":"comparacion-de-amlo-sobre-pandemia-de-covid-19-no-ayuda-a-mexicanos-espana","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/comparacion-de-amlo-sobre-pandemia-de-covid-19-no-ayuda-a-mexicanos-espana\/","title":{"rendered":"Comparaci\u00f3n de AMLO sobre pandemia de Covid-19 no ayuda a mexicanos: Espa\u00f1a"},"content":{"rendered":"\n<p>La comparaci\u00f3n que hizo el presidente Andr\u00e9s Manuel L\u00f3pez Obrador sobre la gesti\u00f3n de la pandemia de Covid-19 en Espa\u00f1a y M\u00e9xico, no ayuda ni resulta muy provechosa a los mexicanos, se\u00f1al\u00f3 la ministra espa\u00f1ola de Asuntos Exteriores, Arancha Gonz\u00e1lez.<\/p>\n\n\n\n<p>La ministra dijo que \u00aba cada ciudadano, lo que le preocupa es lo que su Gobierno est\u00e1 haciendo para protegerle a \u00e9l y para proteger su econom\u00eda\u00bb.<\/p>\n\n\n\n<p>Cabe recordar que el lunes, el mandatario mexicano se\u00f1al\u00f3 que \u00absi se compara a&nbsp;M\u00e9xico, vamos a decir, con Espa\u00f1a, y ofrezco disculpas al pueblo espa\u00f1ol y al Gobierno espa\u00f1ol, en las dos crisis, la sanitaria y la econ\u00f3mica, nos ha ido mejor a nosotros\u00bb.<\/p>\n\n\n\n<p>La ministra espa\u00f1ola replic\u00f3 que \u201ceste tipo de comparativas, yo creo que no ayudan, no creo que les resulten muy \u00fatiles a los ciudadanos mexicanos, como si yo hiciera el comentario opuesto\u00bb.<\/p>\n\n\n\n<p>Arancha Gonz\u00e1lez Laya argument\u00f3 que no le consolar\u00eda mucho al ciudadano espa\u00f1ol que ella dijera que Espa\u00f1a lo est\u00e1 haciendo mucho mejor que su vecino.<\/p>\n\n\n\n<p>\u00abLo que importa ahora es dar la confianza a nuestros ciudadanos, que nuestra acci\u00f3n gubernamental, tanto en lo sanitario, como en lo econ\u00f3mico, financiero&#8230; responde a las necesidades del pa\u00eds\u00bb, apunt\u00f3.<\/p>\n\n\n\n<p>Fuente: El Universal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comparaci\u00f3n que hizo el presidente Andr\u00e9s Manuel L\u00f3pez Obrador sobre la gesti\u00f3n de la pandemia de Covid-19 en Espa\u00f1a y M\u00e9xico, no ayuda ni resulta muy provechosa a los mexicanos, se\u00f1al\u00f3 la ministra espa\u00f1ola de Asuntos Exteriores, Arancha Gonz\u00e1lez. La ministra dijo que \u00aba cada ciudadano, lo que le preocupa es lo que su<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/comparacion-de-amlo-sobre-pandemia-de-covid-19-no-ayuda-a-mexicanos-espana\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":52486,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/08\/1116809.jpg?fit=1024%2C637&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dEx","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52485"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=52485"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/52486"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=52485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=52485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=52485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}