{"id":52525,"date":"2020-08-19T09:46:32","date_gmt":"2020-08-19T14:46:32","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=52525"},"modified":"2020-08-19T10:25:07","modified_gmt":"2020-08-19T15:25:07","slug":"tribunal-niega-amparo-a-rosario-robles-y-ratifica-vinculacion-a-proceso-por-estafa-maestra","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/tribunal-niega-amparo-a-rosario-robles-y-ratifica-vinculacion-a-proceso-por-estafa-maestra\/","title":{"rendered":"Tribunal niega amparo a Rosario Robles y ratifica vinculaci\u00f3n a proceso por &#8216;Estafa Maestra&#8217;"},"content":{"rendered":"\n<p>Un tribunal colegiado ratific\u00f3 una negativa de amparo contra Rosario Robles y dej\u00f3 firme el&nbsp;auto de vinculaci\u00f3n a proceso en su contra por el caso de la &#8216;Estafa Maestra&#8217;,&nbsp;dictado en audiencia del 12 y 13 de agosto de 2019 por el juez Felipe de Jes\u00fas Delgadillo Padierna, sobrino de la senadora Dolores Padierna.<\/p>\n\n\n\n<p>\u201cLa Justicia de la Uni\u00f3n no ampara ni protege a Mar\u00eda del Rosario Robles Berlanga contra el acto reclamado consistente en la vinculaci\u00f3n a proceso\u201d, resolvi\u00f3 por el Tribunal Colegiado.<\/p>\n\n\n\n<p>De acuerdo con la sentencia publicada el martes, los tres magistrados integrantes del Tribunal Colegiado determinaron por unanimidad que los argumentos de Robles Berlanga resultaron \u201cinoperantes e infundados\u201d.<\/p>\n\n\n\n<p>Al impugnar la vinculaci\u00f3n a proceso, en primera instancia, la exsecretaria de Estado acus\u00f3 como conceptos de violaci\u00f3n la existencia de un \u201cefecto corruptor\u201d por parte de la Fiscal\u00eda General de la Rep\u00fablica (FGR) quien inici\u00f3 la investigaci\u00f3n en su contra casi cuatro a\u00f1os despu\u00e9s de que se cometieron los supuestos delitos.<\/p>\n\n\n\n<p>Dijo que la indagatoria de la FGR no tuvo un sustento documental, pero s\u00ed una base subjetiva a partir de un reportaje hecho con una clara \u201cl\u00ednea editorial\u201d.<\/p>\n\n\n\n<p>Record\u00f3 que en la&nbsp;Auditor\u00eda Superior, en sus dict\u00e1menes t\u00e9cnicos no la se\u00f1al\u00f3 ni denunci\u00f3 penalmente como responsable de las acciones u omisiones que se le imputaron, y destac\u00f3 que hubo una insuficiencia de los datos de prueba para emitir la vinculaci\u00f3n a proceso en su contra.<\/p>\n\n\n\n<p>Robles tambi\u00e9n acus\u00f3 que en la audiencia en la que se le vincul\u00f3 a proceso el juez Delgadillo Padierna actu\u00f3 con animadversi\u00f3n, encono y consigna en su contra, adem\u00e1s de que pretendi\u00f3 asesorar al Ministerio P\u00fablico para que solicitara medidas cautelares.<\/p>\n\n\n\n<p>\u201cIncluso, se\u00f1alo, en forma ir\u00f3nica, que era inaudito que inicialmente no se solicitara medida cautelar\u201d, destac\u00f3.<\/p>\n\n\n\n<p>Robles agreg\u00f3 que Delgadillo Padierna \u201cen franca vulneraci\u00f3n tanto del deber de imparcialidad y al derecho humano de la Tutela efectiva, no se declar\u00f3 impedido, pese a ser familiar de la senadora Dolores Padierna quien fuera declarada enemiga pol\u00edtica de la imputada\u201d.<\/p>\n\n\n\n<p>Del juez de Amparo, quien desestim\u00f3 los argumentos antes citados, coment\u00f3 que al negarle el amparo en primera instancia, el 31 de enero de 2020, tuvo una falta de fundamentaci\u00f3n, motivaci\u00f3n y exaistivudad; adem\u00e1s de que fue omiso en reparar evidentes violaciones a derechos humanos.<\/p>\n\n\n\n<p>Lo acus\u00f3 tambi\u00e9n de que inadvirti\u00f3 el efecto corruptor y vulner\u00f3 el derecho humano a la exacta aplicaci\u00f3n de la Ley y el principio Pro persona. Mencion\u00f3 que ello deriv\u00f3 en la violaci\u00f3n al debido proceso.<\/p>\n\n\n\n<p>Al respecto, en su sentencia de 776 p\u00e1ginas dictada el 23 de julio pasado y notificada el martes, el Tribunal Colegiado desestim\u00f3 todos y cada uno de los argumentos de Robles. Unos los calific\u00f3 de inoperantes y otros de infundados.<\/p>\n\n\n\n<p>Consider\u00f3 que, al dictar la vinculaci\u00f3n a proceso, el Juez Delgadillo Padierna, de manera correcta, verific\u00f3 que los datos de prueba que constan en la carpeta judicial son aptos y suficientes para tener por acreditado el hecho que la ley se\u00f1ala como delito Ejercicio Indebido del Servicio P\u00fablico (Diversos Dos) continuado.<\/p>\n\n\n\n<p>Sobre la negativa de amparo, indic\u00f3 que no se advirti\u00f3 que se haya vulnerado la esfera jur\u00eddica de Robles, \u201cpues del an\u00e1lisis integral del acto reclamado se desprende que se examin\u00f3 la totalidad de los datos de prueba y no se desprende que se les haya dado un alcance distinto a lo establecido en la Ley\u201d<\/p>\n\n\n\n<p>Cabe destacar que en el expediente se transcriben de manera \u00edntegra las versiones p\u00fablicas de las audiencias del 8 y 12 de de agosto, esta \u00faltima que se prolong\u00f3 hasta el d\u00eda 13.<\/p>\n\n\n\n<p>En dichas audiencias, los representantes de la Fiscal\u00eda General de la Rep\u00fablica (FGR) detallaron la imputaci\u00f3n contra Robles por la llamada &#8216;Estafa Maestra&#8217; y le imputaron la omisi\u00f3n de denunciar o impedir en el desv\u00edo de 5 mil 73 millones de pesos del erario federal.<\/p>\n\n\n\n<p>Detall\u00f3 que desde su posici\u00f3n de titular de las secretar\u00edas de Desarrollo Social (Sedesol) y Desarrollo Agrario, Territorial y Urbano (Sedatu) supo de las irregularidades en el manejo de los recursos pero omiti\u00f3 informar a su superior jer\u00e1rquico, el Presidente de la Rep\u00fablica, y tampoco hizo nada para evitarlo.<\/p>\n\n\n\n<p>Fuente: El Financiero<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un tribunal colegiado ratific\u00f3 una negativa de amparo contra Rosario Robles y dej\u00f3 firme el&nbsp;auto de vinculaci\u00f3n a proceso en su contra por el caso de la &#8216;Estafa Maestra&#8217;,&nbsp;dictado en audiencia del 12 y 13 de agosto de 2019 por el juez Felipe de Jes\u00fas Delgadillo Padierna, sobrino de la senadora Dolores Padierna. \u201cLa Justicia<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/tribunal-niega-amparo-a-rosario-robles-y-ratifica-vinculacion-a-proceso-por-estafa-maestra\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":52526,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,40,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/08\/1116934.jpg?fit=1024%2C683&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dFb","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52525"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=52525"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/52526"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=52525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=52525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=52525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}