{"id":52605,"date":"2020-08-20T12:06:11","date_gmt":"2020-08-20T17:06:11","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=52605"},"modified":"2020-08-20T12:06:16","modified_gmt":"2020-08-20T17:06:16","slug":"zacatecas-es-un-nudo-de-comunicaciones-en-rutas-de-drogas-y-armas-sedena","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/zacatecas-es-un-nudo-de-comunicaciones-en-rutas-de-drogas-y-armas-sedena\/","title":{"rendered":"Zacatecas es un nudo de comunicaciones en rutas de drogas y armas: Sedena"},"content":{"rendered":"\n<p>El titular de la Secretar\u00eda de la Defensa Nacional (Sedena), Luis Cresencio Sandoval, inform\u00f3 que el Ej\u00e9rcito ha detectado varias rutas de enervantes y armas en el pa\u00eds, cuyo centro de comunicaciones se encuentra en Zacatecas. Esto, a su vez, genera un aumento en los \u00edndices delictivos y una tendencia al alza en los homicidios dolosos en el estado.<\/p>\n\n\n\n<p>En\u00a0la ma\u00f1anera\u00a0del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, el secretario de Defensa dio a conocer que Zacatecas, aun sin ser un estado fronterizo ni tener una gran cantidad de ductos o presencia de grupos delincuenciales,\u00a0ocupa el d\u00e9cimo lugar en homicidios dolosos a nivel nacional.<\/p>\n\n\n\n<p>Ante esto, present\u00f3 un mapa del comportamiento en el tr\u00e1fico de drogas, en el que es posible apreciar que las rutas del Golfo, el Pac\u00edfico y el Centro convergen en Zacatecas hacia el norte, y se usan para el transporte de armamento en sentido contrario.<\/p>\n\n\n\n<p>\u201cEs la ruta de enervantes y armas. Zacatecas es un nudo de comunicaciones, pueden ir hacia Tampico, Monterrey, Guadalajara,\u00a0la regi\u00f3n de La Laguna, la parte del Pacifico, conectarse a Guanajuato, Jalisco, y se convierte en nudo de comunicaciones\u201d, dijo el titular de la Sedena.<\/p>\n\n\n\n<p>Cresencio Sandoval record\u00f3 los grupos delictivos en Zacatecas buscan hacer m\u00e1s fuerte su presencia en la regi\u00f3n, y poder asegurar su cargamento il\u00edcito con el fin de hacerlo\u00a0llegar a puntos de inter\u00e9s en la Rep\u00fablica.<\/p>\n\n\n\n<p>\u201cHay concentraci\u00f3n de armas para poderlos hacerlos llegar a grupos delictivos en el pa\u00eds. Con base en esto, pensamos que es el por qu\u00e9 se genera violencia en el estado, porque hay confrontaciones porque se generan estos homicidios, actividad y presencia en el estado\u201d, concluy\u00f3.<\/p>\n\n\n\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de la Secretar\u00eda de la Defensa Nacional (Sedena), Luis Cresencio Sandoval, inform\u00f3 que el Ej\u00e9rcito ha detectado varias rutas de enervantes y armas en el pa\u00eds, cuyo centro de comunicaciones se encuentra en Zacatecas. Esto, a su vez, genera un aumento en los \u00edndices delictivos y una tendencia al alza en los homicidios<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/zacatecas-es-un-nudo-de-comunicaciones-en-rutas-de-drogas-y-armas-sedena\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":52606,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/08\/luis-cresencio-sandoval-gonzalez-actual-1.jpg?fit=958%2C596&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dGt","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52605"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=52605"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52605\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/52606"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=52605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=52605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=52605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}