{"id":52879,"date":"2020-08-26T14:44:26","date_gmt":"2020-08-26T19:44:26","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=52879"},"modified":"2020-08-26T14:44:32","modified_gmt":"2020-08-26T19:44:32","slug":"manifestantes-entran-a-la-fuerza-a-evento-de-amlo-en-gomez-palacio","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/manifestantes-entran-a-la-fuerza-a-evento-de-amlo-en-gomez-palacio\/","title":{"rendered":"Manifestantes entran a la fuerza a evento de AMLO en G\u00f3mez Palacio"},"content":{"rendered":"\n<p>Un grupo de personas ingres\u00f3 a las instalaciones de la Feria de G\u00f3mez Palacio, en Durango, para exigir que el presidente Andr\u00e9s Manuel L\u00f3pez Obrador atienda sus demandas.<\/p>\n\n\n\n<p>Los manifestantes, que dijeron ser simpatizantes de\u00a0L\u00f3pez Obrador,\u00a0reclamaron que hab\u00edan \u201cprivatizado\u201d al titular del Ejecutivo, porque el mandatario solo se reun\u00eda con los gobernadores de Coahuila, Miguel Riquelme (PRI) y de Durango, Jos\u00e9 Rosas Aispuro, (PAN), y a ellos los dejaron afuera.<\/p>\n\n\n\n<p>Los ciudadanos que lograron ingresar se dirig\u00edan al sitio donde se llevaba a cabo la presentaci\u00f3n del proyecto\u00a0&#8216;Agua Saludable para La Laguna&#8217;, que busca mejorar el servicio de agua potable en la regi\u00f3n.<\/p>\n\n\n\n<p>Al respecto, los manifestantes denunciaron que \u201cel proyecto de agua solo beneficiar\u00e1 a los empresarios lecheros de La Laguna y no al pueblo\u201d.<\/p>\n\n\n\n<p>A solo 100 metros del estrado donde se encontraba el mandatario mexicano, elementos de la Polic\u00eda Estatal y personal militar lograron retener a los ciudadanos y evitaron que brincaran las vallas del segundo filtro de seguridad.<\/p>\n\n\n\n<p>Fuente: Radio F\u00f3rmula<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de personas ingres\u00f3 a las instalaciones de la Feria de G\u00f3mez Palacio, en Durango, para exigir que el presidente Andr\u00e9s Manuel L\u00f3pez Obrador atienda sus demandas. Los manifestantes, que dijeron ser simpatizantes de\u00a0L\u00f3pez Obrador,\u00a0reclamaron que hab\u00edan \u201cprivatizado\u201d al titular del Ejecutivo, porque el mandatario solo se reun\u00eda con los gobernadores de Coahuila, Miguel<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/manifestantes-entran-a-la-fuerza-a-evento-de-amlo-en-gomez-palacio\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":52880,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/08\/AMLO-Durango.jpg?fit=1040%2C589&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dKT","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52879"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=52879"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/52879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/52880"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=52879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=52879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=52879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}