{"id":53061,"date":"2020-08-31T10:37:55","date_gmt":"2020-08-31T15:37:55","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=53061"},"modified":"2020-08-31T10:55:55","modified_gmt":"2020-08-31T15:55:55","slug":"bajo-medidas-sanitarias-inicia-el-examen-de-ingreso-a-la-uv","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/bajo-medidas-sanitarias-inicia-el-examen-de-ingreso-a-la-uv\/","title":{"rendered":"Bajo medidas sanitarias, inicia el examen de ingreso a la UV"},"content":{"rendered":"\n<p>A partir de hoy y hasta el 4 de septiembre, los aspirantes a ingresar a la Universidad Veracruzana (UV) presentar\u00e1n el examen de admisi\u00f3n. Se prev\u00e9 la asistencia de m\u00e1s de 38 mil personas en todas las sedes.<\/p>\n\n\n\n<p>En los accesos de cada sede se cuenta con un filtro sanitario en el que se les toma temperatura, se les coloca gel y se hace un cuestionario; adem\u00e1s, cuentan con un m\u00f3dulo m\u00e9dico.&nbsp;<\/p>\n\n\n\n<p>La universidad inform\u00f3 que desde semanas atr\u00e1s, se realizaron diferentes actividades limpieza y desinfecci\u00f3n de los espacios, adem\u00e1s de que se colocaron se\u00f1al\u00e9ticas y marcas en el piso para mantener la sana distancia de 1.5 metros.<\/p>\n\n\n\n<p>La apertura de las sedes es a partir de las 8 de la ma\u00f1ana; el examen inicia a las 10 y se prev\u00e9 que dure tres horas.&nbsp;<\/p>\n\n\n\n<p>Para presentar el examen es obligatorio el uso&nbsp; de cubrebocas, llevar l\u00e1piz, sacapuntas, goma de borrar y calculadora sencilla.<\/p>\n\n\n\n<p>Autoridades acad\u00e9micas recomendaron que los padres y familiares no acompa\u00f1aran a los aspirantes para evitar aglomeraciones, pero en el exterior del campus Mocambo se observa la presencia de padres de familia.<\/p>\n\n\n\n<p>Fuente: Xeu Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de hoy y hasta el 4 de septiembre, los aspirantes a ingresar a la Universidad Veracruzana (UV) presentar\u00e1n el examen de admisi\u00f3n. Se prev\u00e9 la asistencia de m\u00e1s de 38 mil personas en todas las sedes. En los accesos de cada sede se cuenta con un filtro sanitario en el que se les<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/bajo-medidas-sanitarias-inicia-el-examen-de-ingreso-a-la-uv\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":53062,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/08\/1118866.jpg?fit=1024%2C683&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-dNP","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/53061"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=53061"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/53061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/53062"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=53061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=53061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=53061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}