{"id":56491,"date":"2020-11-03T12:02:20","date_gmt":"2020-11-03T18:02:20","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=56491"},"modified":"2020-11-03T12:02:28","modified_gmt":"2020-11-03T18:02:28","slug":"ante-cualquier-resultado-en-ee-uu-tenemos-estabilidad-economica-afirma-lopez-obrador","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/ante-cualquier-resultado-en-ee-uu-tenemos-estabilidad-economica-afirma-lopez-obrador\/","title":{"rendered":"Ante cualquier resultado en EE. UU., tenemos estabilidad econ\u00f3mica, afirma L\u00f3pez Obrador"},"content":{"rendered":"\n<p>En el marco de las elecciones presidenciales en Estados Unidos, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador asegur\u00f3 que sin importar el resultado, M\u00e9xico tiene garant\u00eda de estabilidad econ\u00f3mica y financiera.<\/p>\n\n\n\n<p>El mandatario destac\u00f3 en Palacio Nacional que la econom\u00eda nacional es s\u00f3lida y el peso mantiene estabilidad, por lo que descart\u00f3 afectaciones tras los comicios estadounidenses y la pandemia por Covid-19.<\/p>\n\n\n\n<p>Al ser cuestionado acerca de si dar\u00e1 un mensaje con motivo de las elecciones en Estados Unidos, en las que participan en actual mandatario Donald Trump y el dem\u00f3crata Joe Biden, L\u00f3pez Obrador precis\u00f3 que no emitir\u00e1 mensaje alguno hasta que no se tengan los resultados de los comicios.<\/p>\n\n\n\n<p>Record\u00f3 que M\u00e9xico debe ser respetuoso de Estados Unidos, no hacer pron\u00f3sticos ni interferir en la vida p\u00fablica de esta naci\u00f3n.<\/p>\n\n\n\n<p>\u201cEsperaremos a que transcurran las elecciones a que se tengan los resultados y voy a informar al pueblo en su momento. Tenemos que ser respetuosos y esperar el momento, no adelantarnos, no hacer pron\u00f3sticos y no tomar partido, porque si no queremos que un extranjero opine sobre lo que sucede en el pa\u00eds, no debemos estar con actitudes injerencistas meti\u00e9ndonos en la vida interna de otro pa\u00eds\u201d, aclar\u00f3.<\/p>\n\n\n\n<p>Record\u00f3 que no actuar\u00e1 como lo hizo el gobierno espa\u00f1ol en 2006 tras el fraude electoral que padeci\u00f3, ya que este reconoci\u00f3 el triunfo de Felipe Calder\u00f3n incluso antes de que las mismas autoridades electorales de M\u00e9xico lo hicieran.<\/p>\n\n\n\n<p>Aclar\u00f3 que si bien la actual administraci\u00f3n estadounidenses ha sido respetuosa con M\u00e9xico y no ha habido acuerdos para que agencias de esa naci\u00f3n intervengan en los asuntos internos, hay temas que ser\u00e1n aclarados una vez pasen los comicios.<\/p>\n\n\n\n<p>Fuente: Exc\u00e9lsior<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de las elecciones presidenciales en Estados Unidos, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador asegur\u00f3 que sin importar el resultado, M\u00e9xico tiene garant\u00eda de estabilidad econ\u00f3mica y financiera. El mandatario destac\u00f3 en Palacio Nacional que la econom\u00eda nacional es s\u00f3lida y el peso mantiene estabilidad, por lo que descart\u00f3 afectaciones tras los comicios<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/ante-cualquier-resultado-en-ee-uu-tenemos-estabilidad-economica-afirma-lopez-obrador\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":56492,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,40,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/11\/2471203.jpg?fit=1024%2C768&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-eH9","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/56491"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=56491"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/56491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/56492"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=56491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=56491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=56491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}