{"id":57275,"date":"2020-11-16T17:44:49","date_gmt":"2020-11-16T23:44:49","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=57275"},"modified":"2020-11-16T17:44:55","modified_gmt":"2020-11-16T23:44:55","slug":"agencia-latinoamericana-y-caribena-espacial-suma-a-seis-paises-arranca-en-2021","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/agencia-latinoamericana-y-caribena-espacial-suma-a-seis-paises-arranca-en-2021\/","title":{"rendered":"Agencia Latinoamericana y Caribe\u00f1a espacial suma a seis pa\u00edses; arranca en 2021"},"content":{"rendered":"\n<p>El secretario de Relaciones Exteriores, Marcelo Ebrard, inform\u00f3 que seis pa\u00edses de Latinoam\u00e9rica se sumaron la Agencia Latinoamericana y Caribe\u00f1a del Espacio (ALCE), lo que suma a ocho pa\u00edses, incluido M\u00e9xico y Argentina, para consolidar el proyecto en 2021.\u00a0<\/p>\n\n\n\n<p>A trav\u00e9s de Twitter, Ebrard asegur\u00f3 que ALCE creci\u00f3 cuatro veces m\u00e1s en un mes y reiter\u00f3 que entrar\u00e1 en operaciones para 2021.\u00a0Los pa\u00edses que se incorporan son Bolivia, Ecuador, El Salvador y Paraguay.\u00a0<\/p>\n\n\n\n<p>Mientras que Colombia y Per\u00fa tambi\u00e9n participar\u00e1n como observadores.<\/p>\n\n\n\n<p>\u00abAvanza la Agencia Latinoamericana y Caribe\u00f1a del Espacio: se incorporan Bolivia, Ecuador, El Salvador y Paraguay. Colombia y Per\u00fa tambi\u00e9n participaron como observadores. Somos ya- con Argentina y M\u00e9xico &#8211; 8 naciones construyendo ALCE para 2021. Crecimos cuatro veces en un mes\u00bb, escribi\u00f3 en Twitter.\u00a0<\/p>\n\n\n\n<p>Ebrard asegur\u00f3 que \u00abcooperando podemos tener mejores resultados para nuestros pueblos [&#8230;] No es solo un ejercicio pol\u00edtico de corto plazo, sino que\u00a0podemos abrir el camino junto con los pa\u00edses de Am\u00e9rica Latina y El Caribe hacia el progreso cient\u00edfico y tecnol\u00f3gico\u00bb.<\/p>\n\n\n\n<p>Durante una reuni\u00f3n virtual respecto a la iniciativa de la Declaraci\u00f3n sobre la Constituci\u00f3n de un Mecanismo Regional de Cooperaci\u00f3n en el \u00c1mbito Espacial, Ebrard insisti\u00f3 en la importancia de esta, pues \u201csi Am\u00e9rica Latina y el Caribe no participa en la carrera espacial, muy probablemente\u00a0vamos a tener cada vez m\u00e1s desventajas en materia cient\u00edfica y tecnol\u00f3gica, que se traduce en debilidad e incapacidad para resolver los problemas que tenemos en materia de bienestar social\u201d.<\/p>\n\n\n\n<p>Por su parte, Jorge Arganis D\u00edaz, secretario de Comunicaciones y Transportes, se\u00f1al\u00f3 que\u00a0la regi\u00f3n ya no estar\u00e1 marginada de grandes proyectos como el regreso del hombre a la luna en 2024, y la exploraci\u00f3n en el planeta Marte con vuelos no tripulados y tripulados.<\/p>\n\n\n\n<p>\u00abCon el talento de nuestras juventudes cient\u00edficas unidas, tendremos la capacidad para contribuir y aportar nuestro grano de arena\u00bb, expres\u00f3 el funcionario.\u00a0<\/p>\n\n\n\n<p>La Declaraci\u00f3n es producto de los acuerdos alcanzados en el Encuentro Latinoamericano y Caribe\u00f1o del Espacio, del 2 de julio de 2020, como parte del plan de trabajo de M\u00e9xico en su calidad de presidencia pro tempore de la Comunidad de Estados Latinoamericanos y Caribe\u00f1os (Celac).&nbsp;<\/p>\n\n\n\n<p>Tiene el prop\u00f3sito fundamental de promover la colaboraci\u00f3n en materia de transferencia tecnol\u00f3gica para la elaboraci\u00f3n de proyectos conjuntos,\u00a0como la puesta en \u00f3rbita del primer nano-sat\u00e9lite de la Comunidad de Estados Latinoamericanos y Caribe\u00f1os\u00a0(Celac-SAT).<\/p>\n\n\n\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Relaciones Exteriores, Marcelo Ebrard, inform\u00f3 que seis pa\u00edses de Latinoam\u00e9rica se sumaron la Agencia Latinoamericana y Caribe\u00f1a del Espacio (ALCE), lo que suma a ocho pa\u00edses, incluido M\u00e9xico y Argentina, para consolidar el proyecto en 2021.\u00a0 A trav\u00e9s de Twitter, Ebrard asegur\u00f3 que ALCE creci\u00f3 cuatro veces m\u00e1s en un mes y<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/agencia-latinoamericana-y-caribena-espacial-suma-a-seis-paises-arranca-en-2021\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":57276,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/11\/mexico-y-argentina-son-los_72_67_1091_679.jpg?fit=958%2C596&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-eTN","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/57275"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=57275"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/57275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/57276"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=57275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=57275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=57275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}