{"id":58023,"date":"2020-11-30T16:17:20","date_gmt":"2020-11-30T22:17:20","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=58023"},"modified":"2020-11-30T16:17:25","modified_gmt":"2020-11-30T22:17:25","slug":"que-se-lo-tome-muy-en-serio-pide-oms-a-mexico-ante-covid-19","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/que-se-lo-tome-muy-en-serio-pide-oms-a-mexico-ante-covid-19\/","title":{"rendered":"\u201cQue se lo tome muy en serio\u201d, pide OMS a M\u00e9xico ante Covid-19"},"content":{"rendered":"\n<p>Tedros Adhanom, director de la Organizaci\u00f3n Mundial de la Salud (OMS),\u00a0declar\u00f3 este lunes que M\u00e9xico se encuentra en \u201cuna mala situaci\u00f3n de cara la pandemia de Covid-19\u2033, estatus que provoc\u00f3 que se duplicaran el n\u00famero de casos y fallecidos entre mediados y finales de noviembre.<\/p>\n\n\n\n<p>\u201cQueremos pedirle a M\u00e9xico que se lo tome muy en serio\u201d,\u00a0dijo el funcionario en una conferencia de prensa dedicada al seguimiento del Covid-19 alrededor del mundo.<\/p>\n\n\n\n<p>\u201cLa situaci\u00f3n en M\u00e9xico es muy preocupante. Los n\u00fameros muestran que el pa\u00eds est\u00e1 en mala situaci\u00f3n. Cuando suben los casos y tambi\u00e9n las muertes es un problema muy serio y pedir\u00edamos a M\u00e9xico que sea serio. Esperamos que todos los l\u00edderes den ejemplo\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Por su parte, Michael Ryan, director de Emergencias Sanitarias de la OMS, dijo que M\u00e9xico \u201csigue gravemente afectado por el Covid-19\u2033, y pidi\u00f3 a todos los l\u00edderes del mundo que \u201ces muy importante que sean muy claros con el uso de mascarillas. La gente requiere comunicaci\u00f3n muy clara. Si lo que ven en un cartel, no lo cumplen las autoridades hay confusi\u00f3n\u201d.<\/p>\n\n\n\n<p>\u201cEstamos pagando todos un precio muy alto por la falta de inversi\u00f3n en preparaci\u00f3n de los sistemas de salud. He visto la amnesia despu\u00e9s de otras crisis. Si seguimos haciendo lo mismo, podemos volver a ver eventos como este o peores durante nuestra vida\u201d, sentenci\u00f3.<\/p>\n\n\n\n<p>De acuerdo con el \u00faltimo reporte de la Secretar\u00eda de Salud, M\u00e9xico registra un mill\u00f3n 107 mil 071 casos positivos y 105 mil 655 decesos.<\/p>\n\n\n\n<p>Entre las entidades con m\u00e1s casos positivos se encuentran la Ciudad de M\u00e9xico con 206 mil 204; Nuevo Le\u00f3n, con 67 mil 165, y Guanajuato con 62 mil 073 casos.<\/p>\n\n\n\n<p>El director general de la OMS tambi\u00e9n inst\u00f3 a los pa\u00edses a no politizar la b\u00fasqueda de los or\u00edgenes del nuevo coronavirus, diciendo que eso solo crear\u00eda barreras para conocer la verdad.<\/p>\n\n\n\n<p>\u201cNecesitamos conocer el origen de este virus porque puede ayudarnos a prevenir futuros brotes\u201d, dijo Tedros. \u201cNo hay nada que ocultar. Queremos saber el origen, y eso es todo\u201d.<\/p>\n\n\n\n<p>Fuente: Infobae<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tedros Adhanom, director de la Organizaci\u00f3n Mundial de la Salud (OMS),\u00a0declar\u00f3 este lunes que M\u00e9xico se encuentra en \u201cuna mala situaci\u00f3n de cara la pandemia de Covid-19\u2033, estatus que provoc\u00f3 que se duplicaran el n\u00famero de casos y fallecidos entre mediados y finales de noviembre. \u201cQueremos pedirle a M\u00e9xico que se lo tome muy en<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/que-se-lo-tome-muy-en-serio-pide-oms-a-mexico-ante-covid-19\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":58024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/11\/G2W6OYPA5ZFHFI4N66NPRH37YA.jpg?fit=768%2C512&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-f5R","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/58023"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=58023"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/58023\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/58024"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=58023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=58023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=58023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}