{"id":58834,"date":"2020-12-17T16:54:36","date_gmt":"2020-12-17T22:54:36","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=58834"},"modified":"2020-12-17T16:54:52","modified_gmt":"2020-12-17T22:54:52","slug":"aprueba-congreso-de-veracruz-minuta-relativa-al-fuero-presidencial","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/aprueba-congreso-de-veracruz-minuta-relativa-al-fuero-presidencial\/","title":{"rendered":"Aprueba Congreso de Veracruz minuta relativa al fuero presidencial"},"content":{"rendered":"\n<p>El Pleno de la LXV Legislatura del Estado de Veracruz aprob\u00f3 la minuta con proyecto de decreto, por la cual se reforman los art\u00edculos 108 y 111 de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos, en materia de fuero presidencial, remitida por la C\u00e1mara de Senadores del Honorable Congreso de la Uni\u00f3n.<\/p>\n\n\n\n<p>En la sesi\u00f3n de este jueves 17 de diciembre, la Comisi\u00f3n Permanente de Justicia y Puntos Constitucionales, conformada por las diputadas M\u00f3nica Robles Barajas, Rosalinda Galindo Silva y Erika Ayala R\u00edos, presidenta, secretaria y vocal, respectivamente, puso a consideraci\u00f3n del Pleno el citado dictamen, mismo que fue avalado por 45 votos, sin abstenciones o votos en contra.<\/p>\n\n\n\n<p>De esta manera, la Legislatura veracruzana da su aval para que sea reformada la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos, toda vez que esta modificaci\u00f3n responde a la necesidad de atender la demanda social de abatir la impunidad que ha generado la protecci\u00f3n constitucional o fuero de los altos servidores p\u00fablicos de la Naci\u00f3n, en este caso el presidente de la Rep\u00fablica, expone el dictamen, que a su vez se\u00f1ala que en este sentido se da un paso firme para avanzar en el combate a la corrupci\u00f3n y la impunidad.<\/p>\n\n\n\n<p>La redacci\u00f3n del segundo p\u00e1rrafo del art\u00edculo 108 de la Constituci\u00f3n General ser\u00e1, \u201cdurante el tiempo de su encargo, el presidente de la Rep\u00fablica podr\u00e1 ser imputado y juzgado por traici\u00f3n a la patria, hechos de corrupci\u00f3n, delitos electorales y todos aquellos delitos por los que podr\u00eda ser enjuiciado cualquier ciudadano o ciudadana\u201d.<\/p>\n\n\n\n<p>El cuarto p\u00e1rrafo del art\u00edculo 111, quedar\u00e1 de la siguiente manera \u201cpara proceder penalmente contra el presidente de la Rep\u00fablica, solo habr\u00e1 lugar a acusarlo ante la C\u00e1mara de Senadores en los t\u00e9rminos del art\u00edculo 110. En este supuesto, la C\u00e1mara de Senadores resolver\u00e1 con base en la legislaci\u00f3n penal aplicable\u201d.<\/p>\n\n\n\n<p>Tras la aprobaci\u00f3n de la Minuta con Proyecto de Decreto, la presidenta de la Mesa Directiva, diputada Adriana Paola Linares Capitanachi, instruy\u00f3 a la Secretar\u00eda General remitir el decreto a la Gaceta Oficial del Estado para su publicaci\u00f3n y, a la vez, enviar la respectiva notificaci\u00f3n al Congreso de la Uni\u00f3n para los fines correspondientes.<\/p>\n\n\n\n<p>Al participar en el debate de este punto del Orden del D\u00eda, la diputada M\u00f3nica Robles Bajaras se\u00f1al\u00f3 que con esta modificaci\u00f3n a la Constituci\u00f3n General se evidencia la voluntad pol\u00edtica y la vocaci\u00f3n democr\u00e1tica del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, \u201cque renuncia y logra convencer al Legislativo para cortar arcaicos privilegios legales y sesgados controles pol\u00edticos que su investidura le otorgaba en la Constituci\u00f3n y por encima de ella, para someterse, sin temor alguno, sin intenci\u00f3n encubierta, ni demagogia alguna, a ser juzgado por otros delitos distintos, al de traici\u00f3n a la Patria\u201d.<\/p>\n\n\n\n<p>Dicha convicci\u00f3n democr\u00e1tica se demuestra tambi\u00e9n, agreg\u00f3, ya que por primera vez en la historia del pa\u00eds, se impulsa la democracia participativa y en el 2022, someterse al juicio del pueblo mediante la revocaci\u00f3n del mandato.<\/p>\n\n\n\n<p>Precis\u00f3, \u201cen Morena sentimos orgullo, ante la humildad de nuestro presidente que predica con el ejemplo de honestidad y austeridad y que sigue como principio rector de sus decisiones, el restablecer la supremac\u00eda del inter\u00e9s p\u00fablico sobre el de las c\u00fapulas del poder econ\u00f3mico para disminuir las enormes desigualdades y solo as\u00ed alcanzar la justicia social y el sue\u00f1o de un pa\u00eds, donde nadie se quede atr\u00e1s\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Pleno de la LXV Legislatura del Estado de Veracruz aprob\u00f3 la minuta con proyecto de decreto, por la cual se reforman los art\u00edculos 108 y 111 de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos, en materia de fuero presidencial, remitida por la C\u00e1mara de Senadores del Honorable Congreso de la Uni\u00f3n. En la<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/aprueba-congreso-de-veracruz-minuta-relativa-al-fuero-presidencial\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":58838,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/12\/5-1.jpg?fit=1024%2C683&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-fiW","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/58834"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=58834"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/58834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/58838"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=58834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=58834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=58834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}