{"id":59025,"date":"2020-12-22T14:58:50","date_gmt":"2020-12-22T20:58:50","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=59025"},"modified":"2020-12-22T14:58:55","modified_gmt":"2020-12-22T20:58:55","slug":"uif-denuncia-ante-fgr-a-la-luz-del-mundo-y-a-su-lider-naason-joaquin-garcia","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/uif-denuncia-ante-fgr-a-la-luz-del-mundo-y-a-su-lider-naason-joaquin-garcia\/","title":{"rendered":"UIF denuncia ante FGR a &#8216;La Luz del Mundo&#8217; y a su l\u00edder, Naas\u00f3n Joaqu\u00edn Garc\u00eda"},"content":{"rendered":"\n<p>La\u00a0Unidad de Inteligencia Financiera (UIF)\u00a0present\u00f3 cinco denuncias ante la Fiscal\u00eda General de la Rep\u00fablica (FGR) en contra de la iglesia\u00a0La Luz del Mundo\u00a0y su l\u00edder, Naas\u00f3n Joaqu\u00edn Garc\u00eda, por delitos fiscales y\u00a0lavado de dinero.<\/p>\n\n\n\n<p>Esta instancia de la Secretear\u00eda de Hacienda y Cr\u00e9dito P\u00fablico (SHCP) detect\u00f3 que tanto esta esta iglesia como su l\u00edder han omitido enterar a las autoridades sobre sus ingresos y, por tanto, \u201chan generado riqueza de manera ilegal\u201d.<\/p>\n\n\n\n<p>La UIF inform\u00f3 que a pesar de que est\u00e1 constituida como organizaci\u00f3n sin fines de lucro, con la denominaci\u00f3n de actividades religiosas, La Luz del Mundo \u201cno guarda relaci\u00f3n con el objeto y los fines para las cuales fueron constituidas\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Servicios de lujo y autos blindados<\/h2>\n\n\n\n<p>Esta unidad encabezada por Santiago Nieto explic\u00f3 que esta iglesia realiz\u00f3 pagos por montos \u201cmuy elevados\u201d para adquirir bienes o servicios \u201cde lujo\u201d como tarjetas de cr\u00e9dito, y veh\u00edculo blindados, entre otros, \u201cque no son acordes al perfil y objeto de las organizaciones sin fines de lucro, con la denominaci\u00f3n de actividades religiosas\u201d.<\/p>\n\n\n\n<p>De igual forma, La Luz del Mundo y su l\u00edder, Naas\u00f3n Joaqu\u00edn Garc\u00eda, realizaron \u201creiteradamente actividades con fines eminentemente lucrativos, como la compra de inmuebles y acciones y el cobro de intereses, mismas que no guardan relaci\u00f3n con el objeto y los fines para las cuales fueron constituidas\u201d.<\/p>\n\n\n\n<p>\u201cReciben recursos financieros por concepto de intereses de diversos instrumentos financieros (realizan inversiones con la finalidad de obtener utilidades). Omisi\u00f3n de manifestar ante la autoridad hacendaria, la obtenci\u00f3n de recursos que son gravables o deducibles para efecto del pago de impuestos.<\/p>\n\n\n\n<p>\u201cRealizan transferencias financieras por altos montos, dirigidas a personas f\u00edsicas y morales con las que no se identifica el tipo de relaci\u00f3n. Las organizaciones sin fines de lucro, con la denominaci\u00f3n de actividades religiosas env\u00edan recursos financieros por cantidades significativas de dinero, mediante transferencias internacionales, personas f\u00edsicas y morales en pa\u00edses clasificados como para\u00edsos fiscales\u201d, detall\u00f3 en una tarjeta informativa.<\/p>\n\n\n\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0Unidad de Inteligencia Financiera (UIF)\u00a0present\u00f3 cinco denuncias ante la Fiscal\u00eda General de la Rep\u00fablica (FGR) en contra de la iglesia\u00a0La Luz del Mundo\u00a0y su l\u00edder, Naas\u00f3n Joaqu\u00edn Garc\u00eda, por delitos fiscales y\u00a0lavado de dinero. Esta instancia de la Secretear\u00eda de Hacienda y Cr\u00e9dito P\u00fablico (SHCP) detect\u00f3 que tanto esta esta iglesia como su l\u00edder han<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/uif-denuncia-ante-fgr-a-la-luz-del-mundo-y-a-su-lider-naason-joaquin-garcia\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":59026,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2020\/12\/naason-joaquin-garcia-santa-cena_0_13_958_595.jpg?fit=958%2C596&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-fm1","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/59025"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=59025"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/59025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/59026"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=59025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=59025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=59025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}