{"id":60254,"date":"2021-01-19T15:33:28","date_gmt":"2021-01-19T21:33:28","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=60254"},"modified":"2021-01-19T15:33:32","modified_gmt":"2021-01-19T21:33:32","slug":"recemos-por-el-exito-del-gobierno-de-biden-trump-da-su-ultimo-mensaje-presidencial","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/recemos-por-el-exito-del-gobierno-de-biden-trump-da-su-ultimo-mensaje-presidencial\/","title":{"rendered":"\u00abRecemos por el \u00e9xito del gobierno de Biden\u00bb: Trump da su \u00faltimo mensaje presidencial"},"content":{"rendered":"\n<p>El presidente saliente de Estados Unidos, Donald Trump, dijo hoy sentirse orgulloso de ser el mandatario que no inici\u00f3 nuevas guerras despu\u00e9s de d\u00e9cadas; solicit\u00f3 adem\u00e1s que se\u00a0\u00abrece\u00bb por el \u00e9xito del gobierno del dem\u00f3crata Joe Biden, que asume el mi\u00e9rcoles, esto luego de enviar\u00a0un mensaje de despedida de su administraci\u00f3n en la Casa Blanca.<\/p>\n\n\n\n<p>\u00abEsta semana, se inaugura una nueva presidencia y recemos por su \u00e9xito para que Estados Unidos siga siendo un lugar seguro y pr\u00f3spero\u00bb, dijo Trump, seg\u00fan los extractos del discurso que la Casa Blanca indic\u00f3 que va a ser difundido muy pronto.<\/p>\n\n\n\n<p>Trump romper\u00e1 la tradici\u00f3n y no acudir\u00e1 a la ceremonia de investidura de su sucesor, y abandonar\u00e1 ma\u00f1ana Washington con destino a su mansi\u00f3n privada en Palm Beach (Florida), horas antes de que Biden llegue a la Casa Blanca.<\/p>\n\n\n\n<p>En su discurso, en el que no mencion\u00f3 a Biden por el nombre, se limit\u00f3 a se\u00f1alar que \u00abrezar\u00e1\u00bb por la nueva Administraci\u00f3n y sac\u00f3 pecho por los logros de sus cuatro a\u00f1os de mandato.<\/p>\n\n\n\n<p>\u00abRevitalizamos nuestras alianzas -recalc\u00f3- e impulsamos a las naciones del mundo a plantar cara a China como nunca antes\u00bb y, como resultado \u00abde la valiente diplomacia y un realismo basado en principios\u00bb, se alcanzaron \u00abhist\u00f3ricos acuerdos de paz en el Oriente Medio\u00bb, dijo.<\/p>\n\n\n\n<p>\u00abEs el amanecer en el nuevo Oriente Miedo y estamos trayendo de vuelta a casa a nuestros soldados\u00bb, sostuvo en referencia a la reducci\u00f3n del n\u00famero de efectivos estadounidenses desplegados en Afganist\u00e1n, Siria e Irak, entre otros lugares.<\/p>\n\n\n\n<p>Fuente: Agencias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente saliente de Estados Unidos, Donald Trump, dijo hoy sentirse orgulloso de ser el mandatario que no inici\u00f3 nuevas guerras despu\u00e9s de d\u00e9cadas; solicit\u00f3 adem\u00e1s que se\u00a0\u00abrece\u00bb por el \u00e9xito del gobierno del dem\u00f3crata Joe Biden, que asume el mi\u00e9rcoles, esto luego de enviar\u00a0un mensaje de despedida de su administraci\u00f3n en la Casa Blanca.<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/recemos-por-el-exito-del-gobierno-de-biden-trump-da-su-ultimo-mensaje-presidencial\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":60255,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,48,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/01\/donald-trump-presidente-de-eu-6_0_0_1200_747.jpg?fit=958%2C596&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-fFQ","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/60254"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=60254"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/60254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/60255"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=60254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=60254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=60254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}