{"id":60828,"date":"2021-01-30T20:58:36","date_gmt":"2021-01-31T02:58:36","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=60828"},"modified":"2021-01-30T20:58:45","modified_gmt":"2021-01-31T02:58:45","slug":"amlo-sigue-presentando-cuadro-leve-de-covid-19-va-a-recuperarse-ssa","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/amlo-sigue-presentando-cuadro-leve-de-covid-19-va-a-recuperarse-ssa\/","title":{"rendered":"AMLO sigue presentando cuadro leve de covid-19, va a recuperarse: Ssa"},"content":{"rendered":"\n<p>El director general de Promoci\u00f3n a la Salud, Ricardo Cort\u00e9s Alcal\u00e1, inform\u00f3 la actualizaci\u00f3n del estado de salud del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, esto despu\u00e9s\u00a0de haber reaparecido en un video el pasado viernes.<\/p>\n\n\n\n<p>\u00abEst\u00e1 presentando un cuadro leve y est\u00e1 con mucha tranquilidad y esperanza, va a recuperarse\u00bb, a\u00f1adi\u00f3 Cort\u00e9s Alcal\u00e1 durante la conferencia de prensa sobre el Covid-19 en M\u00e9xico.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 que se cumplir\u00e1 este domingo\u00a0su primera semana en aislamiento, tras haber dado positivo a Covid-19, y reiter\u00f3 que deben ser 14 d\u00edas, como m\u00ednimo, para poder retomar sus actividades<\/p>\n\n\n\n<p>\u00abRecordemos que son 14 d\u00edas desde que inici\u00f3 con el cuadro cl\u00ednico. Mismos que deber\u00e1n cumplir sus contactos que presenten un resultado positivo\u00bb, dijo el funcionario.<\/p>\n\n\n\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director general de Promoci\u00f3n a la Salud, Ricardo Cort\u00e9s Alcal\u00e1, inform\u00f3 la actualizaci\u00f3n del estado de salud del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, esto despu\u00e9s\u00a0de haber reaparecido en un video el pasado viernes. \u00abEst\u00e1 presentando un cuadro leve y est\u00e1 con mucha tranquilidad y esperanza, va a recuperarse\u00bb, a\u00f1adi\u00f3 Cort\u00e9s Alcal\u00e1 durante la conferencia<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/amlo-sigue-presentando-cuadro-leve-de-covid-19-va-a-recuperarse-ssa\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":60829,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/01\/lopez-obrador-mantenido-cuidados-menores_0_63_1024_637.jpg?fit=958%2C596&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-fP6","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/60828"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=60828"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/60828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/60829"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=60828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=60828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=60828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}