{"id":61684,"date":"2021-02-17T10:11:09","date_gmt":"2021-02-17T16:11:09","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=61684"},"modified":"2021-02-17T10:11:15","modified_gmt":"2021-02-17T16:11:15","slug":"mas-de-89-mil-personas-en-chihuahua-y-tamaulipas-siguen-sin-luz-cfe","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/mas-de-89-mil-personas-en-chihuahua-y-tamaulipas-siguen-sin-luz-cfe\/","title":{"rendered":"M\u00e1s de 89 mil personas en Chihuahua y Tamaulipas siguen sin luz: CFE"},"content":{"rendered":"\n<p>La Comisi\u00f3n Federal de Electricidad (CFE) inform\u00f3 que, al corte de las 06:00 horas de este mi\u00e9rcoles, se encuentran sin suministro de energ\u00eda el\u00e9ctrica 89 mil 183 usuarios en los estados de Chihuahua y Tamaulipas.<\/p>\n\n\n\n<p>Esto representa el 0.21 por ciento de los usuarios totales en los estados afectados y el 0.2 por ciento del total de usuarios de la CFE.<\/p>\n\n\n\n<p>A continuaci\u00f3n, el comunicado:<\/p>\n\n\n\n<p>\u00abEl 15 de febrero del 2021, entre 6:19 a 6:32 horas oper\u00f3 el Disparo Autom\u00e1tico de Carga (interrupci\u00f3n del suministro), por d\u00e9ficit de generaci\u00f3n en el norte y noreste del pa\u00eds, quedando sin suministro 4.8 millones de usuarios, en los estados de Nuevo Le\u00f3n, Coahuila, Tamaulipas, Chihuahua, Zacatecas y Durango. A las 16:30 horas se alcanz\u00f3 un restablecimiento del 79 % de los usuarios afectados.<\/p>\n\n\n\n<p>El mismo d\u00eda, el CENACE, alrededor de las 19:30 horas, solicit\u00f3 un nuevo tiro de carga (interrupci\u00f3n del suministro) con el prop\u00f3sito de estabilizar el Sistema El\u00e9ctrico Nacional, afectando el suministro de 5.9 millones de usuarios en 23 estados de pa\u00eds.<\/p>\n\n\n\n<p>El 16 de febrero 2021, a las 17:30 horas, se ten\u00edan 540 mil usuarios afectados en los estados de Chihuahua, Coahuila, Nuevo Le\u00f3n y Tamaulipas.<\/p>\n\n\n\n<p>Posteriormente, el CENACE instruy\u00f3 un nuevo tiro de carga y, a las 19:00 horas, se encontraban sin suministro el\u00e9ctrico 3.2 millones de usuarios, en 26 estados del pa\u00eds, que representan menos del 8 % de los usuarios totales en dichos estados.<\/p>\n\n\n\n<p>Considerando que los tiros de carga son aleatorios y rotativos, a las 22:30 horas, se encontraban sin suministro el\u00e9ctrico 713 mil usuarios, en 4 estados del pa\u00eds, que representan el 1.6 % de los usuarios totales en los estados afectados y el 1.5 % del total de usuarios de la CFE.<\/p>\n\n\n\n<p>Los usuarios se rotan para no afectarse por largos per\u00edodos.<\/p>\n\n\n\n<p>A las 6:00 horas, del d\u00eda de hoy, se encuentran sin suministro 89,183 usuarios, en los estados de Chihuahua y Tamaulipas, que representan 0.21% de los usuarios totales en los estados afectados y el 0.2 % del total de usuarios de la CFE.<\/p>\n\n\n\n<p>Es de resaltar que, la CFE ha puesto a disposici\u00f3n del CENACE todas sus plantas de generaci\u00f3n, para lograr el balance carga-generaci\u00f3n, con lo que se han disminuido los tiros de carga.<\/p>\n\n\n\n<p>Se tiene estrecha coordinaci\u00f3n con el CENACE para mantener la estabilidad del sistema el\u00e9ctrico y evitar una afectaci\u00f3n mayor, as\u00ed como para atender las actividades de restablecimiento que instruya\u00bb.<\/p>\n\n\n\n<p>Fuente: Xeu Noticias<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Federal de Electricidad (CFE) inform\u00f3 que, al corte de las 06:00 horas de este mi\u00e9rcoles, se encuentran sin suministro de energ\u00eda el\u00e9ctrica 89 mil 183 usuarios en los estados de Chihuahua y Tamaulipas. Esto representa el 0.21 por ciento de los usuarios totales en los estados afectados y el 0.2 por ciento del<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/mas-de-89-mil-personas-en-chihuahua-y-tamaulipas-siguen-sin-luz-cfe\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":61685,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/02\/1144598.jpg?fit=1024%2C683&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-g2U","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/61684"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=61684"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/61684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/61685"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=61684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=61684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=61684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}