{"id":63013,"date":"2021-03-13T14:17:45","date_gmt":"2021-03-13T20:17:45","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=63013"},"modified":"2021-03-13T14:40:42","modified_gmt":"2021-03-13T20:40:42","slug":"detienen-a-rogelio-franco-exsecretario-de-gobierno-de-veracruz","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/detienen-a-rogelio-franco-exsecretario-de-gobierno-de-veracruz\/","title":{"rendered":"Detienen a Rogelio Franco, exsecretario de Gobierno de Veracruz"},"content":{"rendered":"\n<p>Elementos de la\u00a0Polic\u00eda Ministerial\u00a0de la\u00a0Fiscal\u00eda General del Estado\u00a0(FGE) detuvieron a\u00a0Rogelio Franco Cast\u00e1n,\u00a0secretario de Gobierno\u00a0durante la administraci\u00f3n de\u00a0Miguel \u00c1ngel Yunes Linares.<\/p>\n\n\n\n<p>La detenci\u00f3n de\u00a0Rogelio Franco\u00a0ocurri\u00f3 en el municipio de\u00a0Tuxpan, al norte del\u00a0Estado. El delito que se le imputa es\u00a0violencia intrafamiliar.<\/p>\n\n\n\n<p>El exdirigente del\u00a0PRD\u00a0fue acusado por su\u00a0exesposa,\u00a0Guillermina Alvarado Gonz\u00e1lez, de golpearla. La\u00a0denuncia\u00a0se hizo p\u00fablica en\u00a0mayo\u00a0de\u00a02020, su\u00a0exesposa\u00a0asegur\u00f3 que el\u00a0exsecretario de Gobierno\u00a0era protegido por el l\u00edder nacional del\u00a0PRD,\u00a0\u00c1ngel \u00c1vila, por lo que la\u00a0denuncia\u00a0no proced\u00eda.<\/p>\n\n\n\n<p>La tambi\u00e9n\u00a0perredista\u00a0subi\u00f3 a\u00a0redes sociales\u00a0las grabaciones en las que se\u00f1alaba a\u00a0Franco Cast\u00e1n\u00a0de golpearla desde hace\u00a030 a\u00f1os,\u00a0y que le dej\u00f3 de tener\u00a0miedo\u00a0a su\u00a0marido\u00a0una vez que perdieron las\u00a0elecciones\u00a0ante\u00a0Morena.<\/p>\n\n\n\n<p>El exsecretario de Gobierno se habr\u00eda opuesto a su detenci\u00f3n, por lo que adem\u00e1s se le fincar\u00eda el delito de ultrajes a la autoridad, considerado grave en la reciente reforma a diversas disposiciones del C\u00f3digo Penal del Estado de Veracruz.<\/p>\n\n\n\n<p>Fuente: La Silla Rota Veracruz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elementos de la\u00a0Polic\u00eda Ministerial\u00a0de la\u00a0Fiscal\u00eda General del Estado\u00a0(FGE) detuvieron a\u00a0Rogelio Franco Cast\u00e1n,\u00a0secretario de Gobierno\u00a0durante la administraci\u00f3n de\u00a0Miguel \u00c1ngel Yunes Linares. La detenci\u00f3n de\u00a0Rogelio Franco\u00a0ocurri\u00f3 en el municipio de\u00a0Tuxpan, al norte del\u00a0Estado. El delito que se le imputa es\u00a0violencia intrafamiliar. El exdirigente del\u00a0PRD\u00a0fue acusado por su\u00a0exesposa,\u00a0Guillermina Alvarado Gonz\u00e1lez, de golpearla. La\u00a0denuncia\u00a0se hizo p\u00fablica en\u00a0mayo\u00a0de\u00a02020, su\u00a0exesposa\u00a0asegur\u00f3 que<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/detienen-a-rogelio-franco-exsecretario-de-gobierno-de-veracruz\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":63014,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/03\/rogeliofranco-focus-0-0-983-557.jpg?fit=1024%2C580&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-gol","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/63013"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=63013"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/63013\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/63014"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=63013"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=63013"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=63013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}