{"id":63758,"date":"2021-03-29T21:01:51","date_gmt":"2021-03-30T03:01:51","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=63758"},"modified":"2021-03-29T21:02:03","modified_gmt":"2021-03-30T03:02:03","slug":"zebadua-sera-citado-a-declarar-en-juicio-contra-rosario-robles","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/zebadua-sera-citado-a-declarar-en-juicio-contra-rosario-robles\/","title":{"rendered":"Zebad\u00faa ser\u00e1 citado a declarar en juicio contra Rosario Robles"},"content":{"rendered":"\n<p>El exoficial mayor de la Secretar\u00eda de Desarrollo Social,\u00a0Emilio Zebad\u00faa, ser\u00e1 citado a declarar como testigo en el proceso penal que enfrenta la extitular de la Sedesol y la Sedatu, Rosario Robles, por el delito de ejercicio indebido del servicio p\u00fablico, en el caso de la &#8216;Estafa Maestra&#8217;.\u00a0<\/p>\n\n\n\n<p>Esto luego de que el\u00a0juez\u00a0Ganther\u00a0Alejandro Villar Ceballos\u00a0admiti\u00f3 la petici\u00f3n de la defensa de Robles de que Zebad\u00faa para que rinda su testimonio sobre su responsabilidad al firmar convenios con universidades, pues debi\u00f3 informar cualquier irregularidad a la exfuncionaria, seg\u00fan explic\u00f3\u00a0Epigmenio Mendieta, abogado de la imputada,\u00a0al concluir la audiencia intermedia que se realiz\u00f3 este lunes en el\u00a0Centro de Justicia Penal Federal del Reclusorio Sur\u00a0y que dur\u00f3 casi cinco horas.<\/p>\n\n\n\n<p>\u201cLogramos la inclusi\u00f3n de\u00a0Emilio Zebad\u00faa, que para nosotros se convierte en un testigo muy importante, pues de acuerdo con la teor\u00eda del caso que defiende esta defensa, consideramos que radica en \u00e9l, por mandato de ley y porque as\u00ed lo establece la propia Ley de Adquisiciones, Arrendamientos y Servicio P\u00fablico, la responsabilidad para la firma de los convenios.\u00a0<\/p>\n\n\n\n<p>\u201cY en su caso, si hab\u00eda alguna irregularidad previa a la firma, \u00e9l tendr\u00eda que haberlo comunicado a\u00a0Rosario Robles, esa informaci\u00f3n no existe, la revisi\u00f3n que se hace de la\u00a0Cuenta P\u00fablica\u00a0se hace a dos a\u00f1os despu\u00e9s de que se ejerci\u00f3 el presupuesto, por lo cual, si estamos en el verbo \u201cevitar\u201d, ya no est\u00e1bamos en la posibilidad de ello\u00bb, explic\u00f3 Mendieta.\u00a0<\/p>\n\n\n\n<p>El juzgador cit\u00f3 este martes para dictar apertura del juicio oral y que est\u00e9 presente Robles, aunque el juicio no puede iniciar porque hay una suspensi\u00f3n definitiva \u00a0en un amparo que promovi\u00f3 la defensa de la exfuncionaria.<\/p>\n\n\n\n<p>Mendieta detall\u00f3 que el juez no acept\u00f3\u00a0la declaraci\u00f3n del actual Auditor Superior de la Federaci\u00f3n, David Colmenares, lo que consider\u00f3 contradictorio porque a la\u00a0Fiscal\u00eda General de la Rep\u00fablica\u00a0(FGR) y a la ASF les admitieron la testimonial del ex titular de la ASF, Manuel Portal.<\/p>\n\n\n\n<p>Fuente: El Heraldo de M\u00e9xico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exoficial mayor de la Secretar\u00eda de Desarrollo Social,\u00a0Emilio Zebad\u00faa, ser\u00e1 citado a declarar como testigo en el proceso penal que enfrenta la extitular de la Sedesol y la Sedatu, Rosario Robles, por el delito de ejercicio indebido del servicio p\u00fablico, en el caso de la &#8216;Estafa Maestra&#8217;.\u00a0 Esto luego de que el\u00a0juez\u00a0Ganther\u00a0Alejandro Villar Ceballos\u00a0admiti\u00f3<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/zebadua-sera-citado-a-declarar-en-juicio-contra-rosario-robles\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":63759,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/03\/f925x521-346941_415805_5050.jpg?fit=1024%2C577&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-gAm","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/63758"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=63758"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/63758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/63759"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=63758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=63758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=63758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}