{"id":64399,"date":"2021-04-12T11:04:12","date_gmt":"2021-04-12T16:04:12","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=64399"},"modified":"2021-04-12T11:04:18","modified_gmt":"2021-04-12T16:04:18","slug":"preven-lluvias-y-viento-en-norte-y-noreste-de-mexico","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/preven-lluvias-y-viento-en-norte-y-noreste-de-mexico\/","title":{"rendered":"Prev\u00e9n lluvias y viento en norte y noreste de M\u00e9xico"},"content":{"rendered":"\n<p>El Servicio Meteorol\u00f3gico Nacional inform\u00f3 que un\u00a0nuevo frente fr\u00edo\u00a0se aproximar\u00e1 e ingresar\u00e1 sobre el norte de la Rep\u00fablica Mexicana, en interacci\u00f3n con una\u00a0l\u00ednea seca\u00a0sobre Coahuila y con un pulso de la\u00a0corriente en chorro subtropical, ocasionando fuertes rachas de viento en el norte y noreste del pa\u00eds, adem\u00e1s de lluvias y chubascos acompa\u00f1ados de descargas el\u00e9ctricas y posibles granizadas en Coahuila, Nuevo Le\u00f3n y Tamaulipas.<\/p>\n\n\n\n<p>Estas condiciones tambi\u00e9n podr\u00edan contribuir a la posible formaci\u00f3n de\u00a0torbellinos o tornados\u00a0en el norte de dichas entidades.<\/p>\n\n\n\n<p>Por otra parte, un\u00a0canal de baja presi\u00f3n\u00a0prevalecer\u00e1 en el noroeste de M\u00e9xico, ocasionando vientos con rachas de 50 a 60 kil\u00f3metros por hora y posibilidad de lluvia aisladas en Baja California.\u00a0<\/p>\n\n\n\n<p>Un\u00a0segundo\u00a0canal de baja presi\u00f3n\u00a0sobre el oriente y sureste del territorio nacional originar\u00e1 lluvias y chubascos vespertinos acompa\u00f1ados de rachas de viento, tormentas el\u00e9ctricas y posibles granizadas en las regiones mencionadas, as\u00ed como en el centro y sur del pa\u00eds.<\/p>\n\n\n\n<p>Finalmente, una\u00a0circulaci\u00f3n anticicl\u00f3nica\u00a0en niveles medios de la atm\u00f3sfera mantendr\u00e1 el ambiente diurno c\u00e1lido a muy caluroso sobre gran parte de la Rep\u00fablica Mexicana. A su vez, se mantendr\u00e1 la\u00a0onda de calor\u00a0sobre entidades del noreste, oriente, sur y sureste de M\u00e9xico, incluida la Pen\u00ednsula de Yucat\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Servicio Meteorol\u00f3gico Nacional inform\u00f3 que un\u00a0nuevo frente fr\u00edo\u00a0se aproximar\u00e1 e ingresar\u00e1 sobre el norte de la Rep\u00fablica Mexicana, en interacci\u00f3n con una\u00a0l\u00ednea seca\u00a0sobre Coahuila y con un pulso de la\u00a0corriente en chorro subtropical, ocasionando fuertes rachas de viento en el norte y noreste del pa\u00eds, adem\u00e1s de lluvias y chubascos acompa\u00f1ados de descargas el\u00e9ctricas<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/preven-lluvias-y-viento-en-norte-y-noreste-de-mexico\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":63282,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/03\/LLUVIA-2.jpg?fit=1024%2C640&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-gKH","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/64399"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=64399"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/64399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/63282"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=64399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=64399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=64399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}