{"id":64852,"date":"2021-04-20T21:43:47","date_gmt":"2021-04-21T02:43:47","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=64852"},"modified":"2021-04-20T21:43:51","modified_gmt":"2021-04-21T02:43:51","slug":"van-mas-de-53-mil-maestros-vacunados-contra-covid-19-con-dosis-de-cansino","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/van-mas-de-53-mil-maestros-vacunados-contra-covid-19-con-dosis-de-cansino\/","title":{"rendered":"Van m\u00e1s de 53 mil maestros vacunados contra Covid-19 con dosis de CanSino"},"content":{"rendered":"\n<p>El director de Epidemiolog\u00eda, Jos\u00e9 Lu\u00eds Alom\u00eda, inform\u00f3 que m\u00e1s de 53 mil docentes\u00a0fueron vacunados contra el Covid-19 este martes\u00a0en cinco entidades del pa\u00eds (Chiapas, Veracruz, Tamaulipas, Coahuila y Nayarit) con la dosis desarrollada por CanSino, esto al corte de las 16:00 horas.<\/p>\n\n\n\n<p>Alom\u00eda explic\u00f3 que los 53 mil 516 maestros de las cinco entidades ya cuentan con sus esquemas completos debido a que la vacuna es solo de una sola dosis, por lo que en tres semanas desarrollar\u00e1n los anticuerpos necesarios para tanto evitar s\u00edntomas graves del Covid-19 como morir a causa del virus SARS-CoV-2.\u00a0<\/p>\n\n\n\n<p>El jefe de Epidemiolog\u00eda explic\u00f3 que se estar\u00e1 anunciado todos los d\u00edas\u00a0el avance de la vacunaci\u00f3n del personal docente. La vacunaci\u00f3n de los maestros busca acelerar el regreso de clases presenciales en todos los niveles educativos.\u00a0<\/p>\n\n\n\n<p>Fuente: Milenio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El director de Epidemiolog\u00eda, Jos\u00e9 Lu\u00eds Alom\u00eda, inform\u00f3 que m\u00e1s de 53 mil docentes\u00a0fueron vacunados contra el Covid-19 este martes\u00a0en cinco entidades del pa\u00eds (Chiapas, Veracruz, Tamaulipas, Coahuila y Nayarit) con la dosis desarrollada por CanSino, esto al corte de las 16:00 horas. Alom\u00eda explic\u00f3 que los 53 mil 516 maestros de las cinco entidades<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/van-mas-de-53-mil-maestros-vacunados-contra-covid-19-con-dosis-de-cansino\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":64853,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,39,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/04\/vacunacion-docentes-inicio-martes-mil_0_45_1024_637.jpg?fit=958%2C596&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-gS0","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/64852"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=64852"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/64852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/64853"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=64852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=64852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=64852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}