{"id":64898,"date":"2021-04-21T21:39:15","date_gmt":"2021-04-22T02:39:15","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=64898"},"modified":"2021-04-21T21:39:29","modified_gmt":"2021-04-22T02:39:29","slug":"comenzara-jornada-de-salud-cuidando-a-mis-peques-2","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/comenzara-jornada-de-salud-cuidando-a-mis-peques-2\/","title":{"rendered":"Comenzar\u00e1 Jornada de Salud &#8216;Cuidando a mis Peques&#8217;"},"content":{"rendered":"\n<p>Al festejarse este mes el D\u00eda del Ni\u00f1o, la Direcci\u00f3n de Salud P\u00fablica Municipal de Coatzacoalcos dar\u00e1 inicio a la Jornada de Salud &#8216;Cuidando a mis Peques&#8217;, en la cual brindar\u00e1 servicios m\u00e9dicos a los infantes del hogar, con lo cual se busca prevenir enfermedades serias o recibir una detecci\u00f3n oportuna.<\/p>\n\n\n\n<p>La jornada es gratuita y se realizar\u00e1 en tres colonias del municipio, a partir de las 9 de la ma\u00f1ana, en los siguientes puntos:<\/p>\n\n\n\n<p>\u25cf 30 de abril en la colonia Divina Providencia, calle Gral. Anaya esq. Esp\u00edritu Santo<br>\u25cf 5 de mayo en la colonia Ampliaci\u00f3n Manantial, calle Huayacocotla y callej\u00f3n Lagarto<br>\u25cf 6 de mayo en la colonia Fertimex, calle Guadalajara y Amoniaco.<\/p>\n\n\n\n<p>Los servicios que se proporcionar\u00e1n ser\u00e1n: consultas m\u00e9dicas, aplicaci\u00f3n de fl\u00faor, toma de tensi\u00f3n arterial, as\u00ed como din\u00e1micas deportivas, tambi\u00e9n se entregar\u00e1n sueros Vida Oral y \u00e1cido f\u00f3lico para mujeres gestantes, en estos d\u00edas tambi\u00e9n habr\u00e1 m\u00f3dulos de vacunaci\u00f3n con Triple Viral, SR, Neumococo, Hexavalente y TDPA para embarazadas.<\/p>\n\n\n\n<p>Para recibir mayores informes podr\u00e1n comunicarse al n\u00famero de tel\u00e9fono 921 21 3 0804, en donde tambi\u00e9n atender\u00e1n a sus dudas.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al festejarse este mes el D\u00eda del Ni\u00f1o, la Direcci\u00f3n de Salud P\u00fablica Municipal de Coatzacoalcos dar\u00e1 inicio a la Jornada de Salud &#8216;Cuidando a mis Peques&#8217;, en la cual brindar\u00e1 servicios m\u00e9dicos a los infantes del hogar, con lo cual se busca prevenir enfermedades serias o recibir una detecci\u00f3n oportuna. La jornada es gratuita<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/comenzara-jornada-de-salud-cuidando-a-mis-peques-2\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":64899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/04\/b1895b5f-e99d-485e-9546-25358595fef4-1.jpg?fit=1280%2C672&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-gSK","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/64898"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=64898"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/64898\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/64899"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=64898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=64898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=64898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}