{"id":65562,"date":"2021-06-08T20:02:25","date_gmt":"2021-06-09T01:02:25","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=65562"},"modified":"2021-06-08T20:02:27","modified_gmt":"2021-06-09T01:02:27","slug":"conmemoran-dia-mundial-de-la-bicicleta-y-medio-ambiente","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/conmemoran-dia-mundial-de-la-bicicleta-y-medio-ambiente\/","title":{"rendered":"Conmemoran D\u00eda Mundial de la Bicicleta y Medio Ambiente"},"content":{"rendered":"\n<p>En conmemoraci\u00f3n del D\u00eda Mundial de la Bicicleta y Medio Ambiente, el Gobierno de Coatzacoalcos, a trav\u00e9s de la Direcci\u00f3n Municipal de Salud P\u00fablica, organiz\u00f3 un recorrido por la ciclopista ubicada en el malec\u00f3n costero de la ciudad.<\/p>\n\n\n\n<p>Esta actividad, que comenz\u00f3 desde muy temprana hora en la pir\u00e1mide del malec\u00f3n, busc\u00f3 promover dos acciones que la poblaci\u00f3n pudiera realizar f\u00e1cilmente, el cuidado de la salud f\u00edsica y del medio ambiente, por lo cual el uso de la bicicleta abarca de forma pr\u00e1ctica estas dos metas, al evitar la contaminaci\u00f3n y ser un ejercicio cardiovascular recomendado.<\/p>\n\n\n\n<p>El Dr. Juan Ram\u00f3n Flores, titular de la Direcci\u00f3n Municipal de Salud P\u00fablica, mencion\u00f3 en entrevista que: \u201cSe busca concientizar a los ciudadanos sobre los beneficios del uso de la bicicleta, que no solo evita contaminar el medio ambiente, aparte ayuda a la salud f\u00edsica de las personas, como a la mejora de la presi\u00f3n arterial, los m\u00fasculos, articulaciones y la presi\u00f3n sangu\u00ednea\u201d.<\/p>\n\n\n\n<p>Durante este d\u00eda, se entregaron plantas a los automovilistas y asistentes, as\u00ed como una conmemorativa vuelta por la ciclopista del Malec\u00f3n Costero, para celebrar los d\u00edas 3 y 5 de junio, respectivamente.<\/p>\n\n\n\n<p>Ana Ruth Mart\u00ednez, nutri\u00f3loga de la Jurisdicci\u00f3n Sanitaria XI y responsable jurisdiccional del programa estatal contra la obesidad, resalt\u00f3 la importancia de este evento, argumentando que \u201cel h\u00e1bito de usar bicicleta, beneficia el cuerpo y el medio ambiente\u00bb.<\/p>\n\n\n\n<p>En su intervenci\u00f3n, el Dr. Gerardo Bajoneros Saavedra, jefe de la Jurisdicci\u00f3n Sanitaria XI, mencion\u00f3 que \u201clos cambios clim\u00e1ticos est\u00e1n relacionados con actividades que realizamos a diario, el fortalecer el uso de la bicicleta como medio de transporte ayudar\u00e1 el entorno ambiental y sobre todo a mantener un estilo de vida saludable\u201d.<\/p>\n\n\n\n<p>Se invita a la poblaci\u00f3n en general a usar la bicicleta como medio de transporte, por su practicidad con el apoyo al cuidado del medio ambiente, y con esto tambi\u00e9n aprovechar los espacios p\u00fablicos que proporciona la ciudad, como lo es el malec\u00f3n y a su vez, beneficiar la salud y el peso de las personas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En conmemoraci\u00f3n del D\u00eda Mundial de la Bicicleta y Medio Ambiente, el Gobierno de Coatzacoalcos, a trav\u00e9s de la Direcci\u00f3n Municipal de Salud P\u00fablica, organiz\u00f3 un recorrido por la ciclopista ubicada en el malec\u00f3n costero de la ciudad. Esta actividad, que comenz\u00f3 desde muy temprana hora en la pir\u00e1mide del malec\u00f3n, busc\u00f3 promover dos acciones<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/conmemoran-dia-mundial-de-la-bicicleta-y-medio-ambiente\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":65563,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/06\/4f0d6f35-c75e-4bb7-be5d-78adeaa26c1e.jpg?fit=1024%2C682&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-h3s","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/65562"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=65562"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/65562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/65563"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=65562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=65562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=65562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}