{"id":65823,"date":"2021-07-12T18:36:54","date_gmt":"2021-07-12T23:36:54","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=65823"},"modified":"2021-07-12T18:36:58","modified_gmt":"2021-07-12T23:36:58","slug":"gobernador-cuitlahuac-garcia-invierte-en-infraestructura-rural-para-desarrollar-los-pueblos-de-veracruz-gomez-cazarin","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/gobernador-cuitlahuac-garcia-invierte-en-infraestructura-rural-para-desarrollar-los-pueblos-de-veracruz-gomez-cazarin\/","title":{"rendered":"Gobernador Cuitl\u00e1huac Garc\u00eda invierte en infraestructura rural para desarrollar los pueblos de Veracruz: G\u00f3mez Cazar\u00edn"},"content":{"rendered":"\n<p>-Gobierno del Estado entrega obras p\u00fablicas en la regi\u00f3n de Los Tuxtlas.<\/p>\n\n\n\n<ul><li>Se inauguraron caminos dignos y electrificaci\u00f3n para las comunidades<\/li><\/ul>\n\n\n\n<p>San Andr\u00e9s Tuxtla, Veracruz., 10 de Julio de 2021.- El crecimiento de las localidades veracruzanas ser\u00e1 posible si se proporcionan las condiciones para un \u00f3ptimo funcionamiento social. Por tal motivo, mejorar la infraestructura rural es un tema prioritario en la agenda p\u00fablica del gobernador Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, declar\u00f3 el Presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica (JUCOPO), diputado Juan Javier G\u00f3mez Cazar\u00edn.<\/p>\n\n\n\n<p>Tras participar en diferentes inauguraciones de construcciones con pavimento en las comunidades de la regi\u00f3n de Los Tuxtlas, el diputado de MORENA, tuvo la oportunidad de saludar a habitantes y reconoci\u00f3 el esfuerzo del Gobierno del Estado, beneficiando a miles de familias de la regi\u00f3n.<\/p>\n\n\n\n<p>De igual forma, se entreg\u00f3 la electrificaci\u00f3n en toda la Barra de Sontecomapan, tras una lucha de varios a\u00f1os de los pobladores de esta localidad, \u00abtoda esta gente no ten\u00eda luz, la ciudadadan\u00eda est\u00e1 muy contenta con el Gobierno de la Cuarta Transformaci\u00f3n\u00bb.<\/p>\n\n\n\n<p>\u201cEs preciso apoyar la productividad de la agricultura, facilitar las v\u00edas esenciales de comunicaci\u00f3n entre localidades y ciudades. Sabemos de la gran preocupaci\u00f3n del gobernador Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, en realizar este tipo de obras con la gesti\u00f3n de nosotros como diputados y la gesti\u00f3n de los alcaldes\u201d, celebr\u00f3 el legislador acompa\u00f1ado del alcalde Julio Ortega Serrano y del titular de SEDESOL, Guillermo Fern\u00e1ndez S\u00e1nchez.<\/p>\n\n\n\n<p>Remarc\u00f3 que estos renovados caminos conectar\u00e1n ciudades y comunidades de municipios de la regi\u00f3n como San Andr\u00e9s Tuxtla, Catemaco y Hueyapan de Ocampo; promoviendo el comercio, el turismo y traslado de ciudadanos entre estos puntos, quienes dejan una derrama econ\u00f3mica importante.<\/p>\n\n\n\n<p>Asimismo, enfatiz\u00f3: \u201cEn este nuevo Gobierno no hay distinci\u00f3n de colores, solamente el beneficio de las y los veracruzanos. El d\u00eda de hoy observamos autoridades comprometidas y convencidas de consolidar el cambio\u201d.<\/p>\n\n\n\n<p>\u201cEl gobernador Cuitl\u00e1huac Garc\u00eda, est\u00e1 muy cercano a la poblaci\u00f3n, donde verdaderamente lo necesitan, la gente que realmente requiere de estas arterias viales\u201d, festej\u00f3 el diputado.<\/p>\n\n\n\n<p>G\u00f3mez Cazar\u00edn asegur\u00f3 que se transforma la vida de las personas que viven en esta zona y la plusval\u00eda tambi\u00e9n incrementa, \u201chay que reconocer la humildad y el deseo de atender a los m\u00e1s desprotegidos, con estas acciones habr\u00e1 cambios significativos\u201d, reiter\u00f3.<\/p>\n\n\n\n<p>Las construcciones inauguradas fueron: el camino EC Sontecomapan-Montep\u00edo en la Barra de Sontecomapan, del tramo del km 3+500 al km 7+200 y la Pavimentaci\u00f3n del camino E.C. Catemaco-Sontecomapan en la zona de Mario Souza, derivado del Fondo de las Entidades Federativas y Municipios Productores de Hidrocarburos.<\/p>\n\n\n\n<p>Fuente: Redacci\u00f3n<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>-Gobierno del Estado entrega obras p\u00fablicas en la regi\u00f3n de Los Tuxtlas. Se inauguraron caminos dignos y electrificaci\u00f3n para las comunidades San Andr\u00e9s Tuxtla, Veracruz., 10 de Julio de 2021.- El crecimiento de las localidades veracruzanas ser\u00e1 posible si se proporcionan las condiciones para un \u00f3ptimo funcionamiento social. Por tal motivo, mejorar la infraestructura rural<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/gobernador-cuitlahuac-garcia-invierte-en-infraestructura-rural-para-desarrollar-los-pueblos-de-veracruz-gomez-cazarin\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":65824,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/07\/12-de-julio.jpg?fit=1024%2C683&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-h7F","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/65823"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=65823"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/65823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/65824"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=65823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=65823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=65823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}