{"id":66042,"date":"2021-08-09T20:05:06","date_gmt":"2021-08-10T01:05:06","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=66042"},"modified":"2021-08-09T20:05:09","modified_gmt":"2021-08-10T01:05:09","slug":"llama-ine-a-analizar-las-propuesta-de-reforma-electoral-por-posibles-retrocesos","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/llama-ine-a-analizar-las-propuesta-de-reforma-electoral-por-posibles-retrocesos\/","title":{"rendered":"Llama INE a analizar las propuesta de reforma electoral por posibles \u201cretrocesos\u201d"},"content":{"rendered":"\n<p>El consejero presidente del\u00a0Instituto Nacional Electoral\u00a0(INE), Lorenzo C\u00f3rdova, llam\u00f3 a las fuerzas pol\u00edticas, sociedad y especialistas a involucrarse, conocer y analizar las propuestas de reformas electorales que se promueven, en las que, dijo, las autoridades electorales pueden aportar con su conocimiento t\u00e9cnico, advirti\u00f3 que pueden implicar\u00a0\u201cfrancos retrocesos\u201d\u00a0a la democracia, regresar a tiempos en los que el gobierno \u201cera juez y parte\u201d.<\/p>\n\n\n\n<p>\u201c (\u2026) en un contexto dominado por la intolerancia y la polarizaci\u00f3n se est\u00e9 empujando, eventualmente, hacia reformas electorales que no necesariamente pueden venir en esta l\u00f3gica de consolidar y fortalecer lo que hasta ahora hemos alcanzado, sino bajo la promesa de transformar radicalmente esta institucionalidad democr\u00e1tica, pueden implicar francos retrocesos\u201d, se\u00f1al\u00f3 C\u00f3rdova durante la inauguraci\u00f3n del\u00a0Foro Virtual\u00a0\u201cEvaluaci\u00f3n y prospectiva de las acciones afirmativas en los procesos electorales federales\u201d \u00a0.<\/p>\n\n\n\n<p>El consejero presidente se\u00f1al\u00f3 que no se pueden perder de vista los\u00a0desaf\u00edos a los que se enfrenta\u00a0\u00a0en este momento el \u00f3rgano electoral ante los ataques y descalificaciones de los que es objeto.<\/p>\n\n\n\n<p>Reconoci\u00f3 que si bien hay \u00e1reas de mejora del modelo electoral, hacia ese objetivo se debe apuntar, \u201ca menos que el objetivo sea regresar a aquellas \u00e9pocas en donde en las elecciones el gobierno era juez y parte\u201d.<\/p>\n\n\n\n<p>Ante representantes de partidos pol\u00edticos, diputados electos, especialistas y consejeros electorales, C\u00f3rdova llam\u00f3 a las fuerzas pol\u00edticas, sociedad y especialistas a involucrarse, conocer y analizar las propuestas de reformas electorales.<\/p>\n\n\n\n<p>\u201cPor ello, es necesario el\u00a0involucramiento de todos los partidos pol\u00edticos\u00a0para conocer y analizar las propuestas de reformas electorales y que la sociedad, los especialistas y las autoridades electorales podamos participar, en nuestro caso, con el aporte t\u00e9cnico que caracteriza nuestro trabajo en la redefinici\u00f3n del andamiaje electoral para que el futuro de nuestra naci\u00f3n sea de una democracia mejor, m\u00e1s robusta y no de una democracia m\u00e1s precaria\u201d, sostuvo\u00a0Lorenzo C\u00f3rdova.\u00a0<\/p>\n\n\n\n<p>Record\u00f3 que la democracia mexicana es producto de los consensos que a lo largo de 45 a\u00f1os sustentaron\u00a0ocho grandes reformas electorales federales,\u00a0en las que se recuperaron las principales demandas de la sociedad en materia de representaci\u00f3n pol\u00edtica, el dise\u00f1o de las instituciones aut\u00f3nomas encargadas de organizar y calificar las elecciones, as\u00ed como las inquietudes para transparentar los procedimientos y el dinero invertido en la competencia electoral.<\/p>\n\n\n\n<p>\u201cEn este 2021, el proceso electoral m\u00e1s grande y complejo de la historia, inici\u00f3 en un contexto francamente adverso para la recreaci\u00f3n de la democracia, ven\u00edamos de m\u00e1s de dos a\u00f1os de ataques al\u00a0INE,\u00a0desde las esferas del poder, de sortear diversas intentonas de reformas electorales, abiertamente regresivas y con un tufo claramente autoritario, sufrimos el\u00a0recorte presupuestal\u00a0m\u00e1s grande la historia en un a\u00f1o con elecciones federales y por si lo anterior no fuera suficiente, m\u00e9xico y el mundo se encuentran en medio de las peores pandemias de los \u00faltimos 100 a\u00f1os\u201d, se\u00f1al\u00f3 la autoridad electoral.\u00a0<\/p>\n\n\n\n<p>En este contexto, dijo que el modelo electoral garantiza la imparcialidad, la inclusi\u00f3n y la paridad en las elecciones federales y locales, se\u00f1al\u00f3 que los criterios aprobados para los\u00a0comicios 2020-2021\u00a0representan un paso m\u00e1s a la democracia inclusiva y paritaria, pero advirti\u00f3 que tambi\u00e9n pueden experimentar un proceso regresivo.<\/p>\n\n\n\n<p>Lo anterior, dio como resultado que en la\u00a0C\u00e1mara de Diputados\u00a0probablemente habr\u00e1 248 diputadas, es decir, del 48.2 por ciento de curules obtenidas por mujeres en 2018, se pas\u00f3 al 49.6 por ciento.\u00a0<\/p>\n\n\n\n<p>En cuanto a los congresos locales, de 673 diputaciones se eligieron a 335 mujeres por el principio de mayor\u00eda relativa y derivado de las acciones afirmativas impulsadas se lograron 65 diputaciones federales para la diversidad y la inclusi\u00f3n.<\/p>\n\n\n\n<p>Fuente: El Heraldo de M\u00e9xico<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El consejero presidente del\u00a0Instituto Nacional Electoral\u00a0(INE), Lorenzo C\u00f3rdova, llam\u00f3 a las fuerzas pol\u00edticas, sociedad y especialistas a involucrarse, conocer y analizar las propuestas de reformas electorales que se promueven, en las que, dijo, las autoridades electorales pueden aportar con su conocimiento t\u00e9cnico, advirti\u00f3 que pueden implicar\u00a0\u201cfrancos retrocesos\u201d\u00a0a la democracia, regresar a tiempos en los que<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/llama-ine-a-analizar-las-propuesta-de-reforma-electoral-por-posibles-retrocesos\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":66043,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,49,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/08\/9-de-agosto-3.jpg?fit=1040%2C585&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-hbc","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/66042"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=66042"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/66042\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/66043"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=66042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=66042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=66042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}