{"id":66446,"date":"2021-10-10T20:09:15","date_gmt":"2021-10-11T01:09:15","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=66446"},"modified":"2021-10-10T20:09:17","modified_gmt":"2021-10-11T01:09:17","slug":"sergio-gutierrez-luna-en-poza-rica-se-reune-con-actores-politicos-empresarios-y-medios","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/sergio-gutierrez-luna-en-poza-rica-se-reune-con-actores-politicos-empresarios-y-medios\/","title":{"rendered":"Sergio Guti\u00e9rrez Luna, en Poza Rica, se re\u00fane con actores pol\u00edticos, empresarios y medios"},"content":{"rendered":"\n<p>*Subraya apoyo efectivo de AMLO al norte de Veracruz<\/p>\n\n\n\n<p>Poza Rica, Ver., 10 de octubre de 2021.- El presidente de la Mesa Directiva de la C\u00e1mara de Diputados, Sergio Guti\u00e9rrez Luna, continu\u00f3 este domingo en Poza Rica su gira de trabajo por el norte del Estado: se reuni\u00f3 con actores pol\u00edticos, empresarios y medios de comunicaci\u00f3n ante quienes reivindic\u00f3 el apoyo efectivo del presidente Andr\u00e9s Manuel L\u00f3pez Obrador con la Huasteca y el Totonacapan veracruzanos.<\/p>\n\n\n\n<p>\u00abEstoy en mi tierra, Veracruz, para comentarles en persona las inversiones que estamos etiquetando en el Presupuesto de Egresos de la Federaci\u00f3n para el 2022\u00bb, dijo ante actores pol\u00edticos de la zona, con quienes se reuni\u00f3 este mediod\u00eda.<\/p>\n\n\n\n<p>Tan solo las inversiones etiquetadas de Pemex, la CFE y la Secretar\u00eda de Comunicaciones en Poza Rica suman 7 mil 300 millones de pesos, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>Pero es muy importante socializarlas, darlas a conocer y discutir con los l\u00edderes pol\u00edticos, empresariales y de opini\u00f3n sus alcances, logros y pendientes, que es lo que estamos haciendo aqu\u00ed, puntualiz\u00f3.<\/p>\n\n\n\n<p>Estuvieron presentes los regidores del Ayuntamiento de Poza Rica, Eloy N\u00fa\u00f1ez Le\u00f3n, Jaime Herrera y Mar\u00eda de la Luz Mora Alarc\u00f3n.<\/p>\n\n\n\n<p>Tambi\u00e9n: Di\u00f3genes Ram\u00edrez Santes, exalcalde de Papantla; Miguel \u00c1ngel Uribe Toral, alcalde electo de Cazones; Abraham Hern\u00e1ndez Hern\u00e1ndez, secretario del Consejo Consultivo de Pueblos Ind\u00edgenas; Ruth Hilda Dom\u00ednguez Hern\u00e1ndez, l\u00edder del Sindicato del Sector Salud; Diego Arturo Torres Hoyos, del sindicato de la UV; entre otros.<\/p>\n\n\n\n<p>M\u00e1s tarde, acompa\u00f1ado de la diputada Federal Mar\u00eda del Carmen Pinete Vargas y de la diputada local Jessica Ram\u00edrez Cisneros, se reuni\u00f3 con el Consejo Empresarial de la Zona Norte, cuyos integrantes son, al mismo tiempo, asociados y l\u00edderes de C\u00e1maras como la de la Construcci\u00f3n, la Canacintra y la Canaco. Los encabez\u00f3 su vicepresidente Jes\u00fas Herrera Franco.<\/p>\n\n\n\n<p>Javier Guti\u00e9rrez Larotta, consejero nacional y vicepresidente de Canacintra, expuso una presentaci\u00f3n en la que explic\u00f3 la necesidad de conectar a Poza Rica con mejores carreteras y con v\u00edas f\u00e9rreas -estas \u00faltimas no existen-, adem\u00e1s de contar con tarifas el\u00e9ctricas acordes a la temperatura ambiental de la zona, condiciones pendientes que actualmente limitan la competitividad de este municipio.<\/p>\n\n\n\n<p>Adolfo Cruz Mabarak, presidente de Canacintra Poza Rica continu\u00f3 diciendo que a pesar de los desaf\u00edos se\u00f1alados las ventajas de Poza Rica tambi\u00e9n son notables: disponibilidad de agua potable, activo humano bien capacitado y s\u00f3lidas vocaciones agroindustriales.<\/p>\n\n\n\n<p>El diputado se dijo cercano a sus problemas dado que las historias recientes de Poza Rica y su natal Minatitl\u00e1n son muy parecidas: de las mieles de una bonanza de la industria petrolera, ambas ciudades pasaron a una depresi\u00f3n de su actividad econ\u00f3mica.<\/p>\n\n\n\n<p>\u00abMe comprometo a construir con ustedes permanentemente, a que busquemos juntos las soluciones, a que el Poder Legislativo y los empresarios sumemos energ\u00edas\u00bb, indic\u00f3.<\/p>\n\n\n\n<p>La jornada de Sergio Guti\u00e9rrez en Poza Rica inici\u00f3 con una tradici\u00f3n local de los domingos por la ma\u00f1ana: desayunando zacahuil en el mercado principal, en el tradicional local de \u00abLa G\u00fcera\u00bb.<\/p>\n\n\n\n<p>Despu\u00e9s ofreci\u00f3 una conferencia de prensa y visit\u00f3 a algunos medios de comunicaci\u00f3n.<\/p>\n\n\n\n<p>Fuente: Redacci\u00f3n <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Subraya apoyo efectivo de AMLO al norte de Veracruz Poza Rica, Ver., 10 de octubre de 2021.- El presidente de la Mesa Directiva de la C\u00e1mara de Diputados, Sergio Guti\u00e9rrez Luna, continu\u00f3 este domingo en Poza Rica su gira de trabajo por el norte del Estado: se reuni\u00f3 con actores pol\u00edticos, empresarios y medios de<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/sergio-gutierrez-luna-en-poza-rica-se-reune-con-actores-politicos-empresarios-y-medios\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":66447,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,42,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2021\/10\/10-de-octubre-3.jpg?fit=1040%2C693&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-hhI","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/66446"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=66446"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/66446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/66447"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=66446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=66446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=66446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}