{"id":67296,"date":"2022-06-06T18:09:57","date_gmt":"2022-06-06T23:09:57","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=67296"},"modified":"2022-06-06T18:10:00","modified_gmt":"2022-06-06T23:10:00","slug":"reciben-vacunas-menores-de-12-a-14-anos-contra-covid-19-en-minatitlan","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/reciben-vacunas-menores-de-12-a-14-anos-contra-covid-19-en-minatitlan\/","title":{"rendered":"Reciben vacunas menores de 12 a 14 a\u00f1os contra Covid-19 en Minatitl\u00e1n"},"content":{"rendered":"\n<p>Se continu\u00f3 aplicando dosis de refuerzo a mayores de 18 a\u00f1os, y para personas que a\u00fan no hab\u00edan recibido ninguna dosis.<\/p>\n\n\n\n<p>Minatitl\u00e1n, Ver. \u2013 Este lunes se llev\u00f3 a cabo la jornada de vacunaci\u00f3n contra covid-19 para menores de 12 a 14 a\u00f1os, del municipio de Minatitl\u00e1n y comunidades aleda\u00f1as, donde desde muy temprana hora se observ\u00f3 una gran afluencia muy importante de padres de familia con sus hijos.<\/p>\n\n\n\n<p>Donde recibieron la segunda dosis de las vacunas Pfizer, AstraZeneca, Cansino y Sinovac seg\u00fan fuera el caso, los m\u00f3dulos de atenci\u00f3n se instalaron en la calle 18 de Octubre esquina Pit\u00e1goras, desde las 8:00 de la ma\u00f1ana a 5:00 de la tarde.<\/p>\n\n\n\n<p>La presidenta municipal Carmen Medel Palma, invit\u00f3 a la ciudadan\u00eda a que sean part\u00edcipes de estas jornadas, con la intenci\u00f3n que cumplan el esquema de vacunaci\u00f3n y reduzcan el n\u00famero de contagios de Covid-19.<\/p>\n\n\n\n<p>\u201cEst\u00e1 campa\u00f1a para adolescentes es de vital importancia, por ello exhort\u00f3 a que seamos ciudadanos responsables y acudamos a vacunarnos, de esta forma cuidamos nuestra salud y la de nuestra familia\u201d indic\u00f3.<\/p>\n\n\n\n<p>De acuerdo a informaci\u00f3n proporcionada por personal de las brigadas, se dio atenci\u00f3n a personas que necesitaban cumplir con el esquema de vacunaci\u00f3n, as\u00ed como personas embarazadas, y personas de la tercera edad pendientes de refuerzos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fuente: Redacci\u00f3n<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se continu\u00f3 aplicando dosis de refuerzo a mayores de 18 a\u00f1os, y para personas que a\u00fan no hab\u00edan recibido ninguna dosis. Minatitl\u00e1n, Ver. \u2013 Este lunes se llev\u00f3 a cabo la jornada de vacunaci\u00f3n contra covid-19 para menores de 12 a 14 a\u00f1os, del municipio de Minatitl\u00e1n y comunidades aleda\u00f1as, donde desde muy temprana hora<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/reciben-vacunas-menores-de-12-a-14-anos-contra-covid-19-en-minatitlan\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":67297,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2022\/06\/6-de-junio-7.jpg?fit=1040%2C693&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-hvq","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/67296"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=67296"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/67296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/67297"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=67296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=67296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=67296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}