{"id":67701,"date":"2022-09-26T23:01:24","date_gmt":"2022-09-27T04:01:24","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=67701"},"modified":"2022-09-26T23:01:29","modified_gmt":"2022-09-27T04:01:29","slug":"27-de-septiembre-parlamento-veracruz-juan-javier-gomez-cazarin","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/27-de-septiembre-parlamento-veracruz-juan-javier-gomez-cazarin\/","title":{"rendered":"27 de septiembre. Parlamento Veracruz. Juan Javier G\u00f3mez Cazar\u00edn*"},"content":{"rendered":"\n<p>XALAPA, VER.- 26 DE SEPTIEMBRE DE 2022<\/p>\n\n\n\n<p>Ma\u00f1ana se conmemora el 201 aniversario de la Consumaci\u00f3n de la Independencia. Nos lo dijeron desde la primaria, \u00bfse acuerdan? En esa fecha, pero de 1821, el famos\u00edsimo Ej\u00e9rcito Trigarante entr\u00f3 a la Ciudad de M\u00e9xico. Se acab\u00f3 la colonia y naci\u00f3 nuestro pa\u00eds.<\/p>\n\n\n\n<p>Y resulta que, tambi\u00e9n ma\u00f1ana, celebramos el 62 aniversario de la Nacionalizaci\u00f3n de la Industria El\u00e9ctrica por el presidente Adolfo L\u00f3pez Mateos.<\/p>\n\n\n\n<p>No s\u00e9 si fue coincidencia o si L\u00f3pez Mateos eligi\u00f3 esa fecha deliberadamente, pero en el contexto mundial y nacional de la actualidad resulta muy oportuno que Independencia y Electricidad coincidan en nuestro calendario.<\/p>\n\n\n\n<p>M\u00e1s oportuno, todav\u00eda, es que Independencia y Electricidad coincidan no s\u00f3lo en las hojas del almanaque sino tambi\u00e9n en las pol\u00edticas p\u00fablicas de la Cuarta Transformaci\u00f3n.<\/p>\n\n\n\n<p>Por el bien de todas y todos, el gobierno del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, con la secretaria de Energ\u00eda, Roc\u00edo Nahle Garc\u00eda, como operadora, ha puesto el inter\u00e9s de mexicanas y mexicanos por delante del inter\u00e9s de las empresas privadas, especialmente de las extranjeras.<\/p>\n\n\n\n<p>Contario a lo que dicen las calumnias, con las pol\u00edticas de la 4T no se dej\u00f3 fuera a las empresas privadas, ni se dio la espalda a las energ\u00edas limpias, nom\u00e1s se le bajaron tres rayitas al encaje tan ancho que pretend\u00edan aplicarle al pueblo de M\u00e9xico.<\/p>\n\n\n\n<p>Gracias a esta Independencia energ\u00e9tica, los precios de la energ\u00eda en M\u00e9xico se han mantenido estables lo m\u00e1s posible, mientras que en otros pa\u00edses las tarifas se han disparado tres o cuatro veces. Eso incluye a Espa\u00f1a, de donde vienen algunas de las empresas que nos quer\u00edan meter la faca.<\/p>\n\n\n\n<p>Una reflexi\u00f3n muy simple: si a esos empresarios espa\u00f1oles les valen queso otros espa\u00f1oles, \u00bfustedes creen que les \u00edbamos a preocupar las y los mexicanos?<\/p>\n\n\n\n<p>Si no fuera por la firme resoluci\u00f3n del presidente L\u00f3pez Obrador, ahorita estar\u00edan haciendo de las suyas en M\u00e9xico.<\/p>\n\n\n\n<p>Por eso, entre otras muchas cosas, estamos orgullosas y orgullosos de tener a este gran Presidente y a esta gran secretaria de Energ\u00eda.<\/p>\n\n\n\n<p>*Diputado local. Presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica del Congreso de Veracruz.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Fuente: Redacci\u00f3n <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XALAPA, VER.- 26 DE SEPTIEMBRE DE 2022 Ma\u00f1ana se conmemora el 201 aniversario de la Consumaci\u00f3n de la Independencia. Nos lo dijeron desde la primaria, \u00bfse acuerdan? En esa fecha, pero de 1821, el famos\u00edsimo Ej\u00e9rcito Trigarante entr\u00f3 a la Ciudad de M\u00e9xico. Se acab\u00f3 la colonia y naci\u00f3 nuestro pa\u00eds. Y resulta que, tambi\u00e9n<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/27-de-septiembre-parlamento-veracruz-juan-javier-gomez-cazarin\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":67702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2022\/09\/27-de-septiembre.jpg?fit=1040%2C652&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-hBX","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/67701"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=67701"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/67701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/67702"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=67701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=67701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=67701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}