{"id":67913,"date":"2023-05-17T17:20:30","date_gmt":"2023-05-17T22:20:30","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=67913"},"modified":"2023-05-17T17:20:35","modified_gmt":"2023-05-17T22:20:35","slug":"reconoce-presidenta-del-congreso-al-poder-judicial-por-sumarse-a-la-austeridad","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/reconoce-presidenta-del-congreso-al-poder-judicial-por-sumarse-a-la-austeridad\/","title":{"rendered":"Reconoce Presidenta del Congreso al Poder Judicial por sumarse a la austeridad"},"content":{"rendered":"\n<p>XALAPA, VER.- 17 DE MAYO DEL 2023<\/p>\n\n\n\n<p>\u2022 Asiste la diputada Margarita Corro a la ceremonia encabezada por el gobernador Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, que da cuenta del compromiso de magistradas y magistrados.<\/p>\n\n\n\n<p>La presidenta de la Mesa Directiva de la LXVI Legislatura del estado, diputada Margarita Corro Mendoza, afirm\u00f3 que la austeridad en un gobierno tiene que ver con el uso eficiente y eficaz del erario, de la infraestructura del Estado, del tiempo del servidor p\u00fablico en su desempe\u00f1o a favor de los gobernados y, sobre todo, de la conducta \u00e9tica. As\u00ed lo manifest\u00f3 al participar en la ceremonia de entrega de reconocimientos a magistradas y magistrados del Poder Judicial estatal.<\/p>\n\n\n\n<p>En el patio central de Palacio de Gobierno, ante el titular del Poder Ejecutivo estatal, ingeniero Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, y la presidenta del Tribunal Superior de Justicia y del Consejo de la Judicatura del Poder Judicial del estado, magistrada Lisbeth Aurelia Jim\u00e9nez Aguirre, la Diputada record\u00f3 que el propio mandatario veracruzano y el presidente Andr\u00e9s Manuel L\u00f3pez Obrador bajaron sus sueldos, impulsaron la austeridad y criticaron fuertemente el modelo de \u201cgobierno rico con pueblo pobre\u201d.<\/p>\n\n\n\n<p>Con la presencia del presidente de la Junta de Coordinaci\u00f3n Pol\u00edtica del Congreso local, diputado Juan Javier G\u00f3mez Cazar\u00edn, la legisladora aclar\u00f3 que la Austeridad Republicana no conlleva la indigencia del Estado y la limitaci\u00f3n de inversi\u00f3n en pol\u00edticas p\u00fablicas de profundo impacto social. Se sum\u00f3 al reconocimiento manifiesto a las y los 22 magistradas y magistrados, as\u00ed como a los dos consejeros del Poder Judicial de Veracruz, por estar comprometidos con las causas sociales y ponderar la austeridad, por encima de cualquier otro inter\u00e9s.<\/p>\n\n\n\n<p>Previamente, indic\u00f3 que no hay peor gobierno en el mundo que aquel cuyos gobernantes viven en la opulencia, mientras sus ciudadanos viven en la pobreza, \u201cm\u00e1xime cuando el fin \u00e9tico de un buen gobierno siempre es generar el bien com\u00fan, impulsando una equitativa distribuci\u00f3n de la riqueza y conminando a que el pueblo trabaje unido y solidariamente en un Estado de Derecho que garantice a mujeres y a hombres los fundamentales derechos que la dignidad humana exige\u201d.<\/p>\n\n\n\n<p>Asimismo, record\u00f3 que en d\u00e9cadas pasadas este pa\u00eds sufri\u00f3 pol\u00edticas impuestas por el capitalismo globalizado que no solamente \u201cachic\u00f3\u201d al Estado, sino que adem\u00e1s adopt\u00f3 una cultura de corrupci\u00f3n, que hizo fraude a la ley y propici\u00f3 la adjudicaci\u00f3n de salarios ofensivos en comparaci\u00f3n con el salario m\u00ednimo de la clase trabajadora.<\/p>\n\n\n\n<p>Tambi\u00e9n, la legisladora Corro Mendoza refiri\u00f3 que en el pasado tener un trabajo en el gobierno no era para servir el bien com\u00fan, sino para los intereses propios. \u201cSe convirti\u00f3 en un fin perverso. No se dio igual en toda la burocracia, sino en las c\u00fapulas, en las \u00e9lites, que en lugar de apoyar al buen funcionamiento de la administraci\u00f3n p\u00fablica, pr\u00e1cticamente la utilizaron para saquearla\u201d.<\/p>\n\n\n\n<p>Por \u00faltimo, reiter\u00f3 que lo hecho por el Presidente y el Gobernador del estado ser\u00e1 un ejemplo para las futuras generaciones que decidan ser parte del servicio p\u00fablico.<\/p>\n\n\n\n<p>Fuente: Redacci\u00f3n<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XALAPA, VER.- 17 DE MAYO DEL 2023 \u2022 Asiste la diputada Margarita Corro a la ceremonia encabezada por el gobernador Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, que da cuenta del compromiso de magistradas y magistrados. La presidenta de la Mesa Directiva de la LXVI Legislatura del estado, diputada Margarita Corro Mendoza, afirm\u00f3 que la austeridad en un gobierno<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/reconoce-presidenta-del-congreso-al-poder-judicial-por-sumarse-a-la-austeridad\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":67914,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2023\/05\/17-de-mayo.jpg?fit=1040%2C691&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-hFn","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/67913"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=67913"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/67913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/67914"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=67913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=67913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=67913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}