{"id":68480,"date":"2024-08-20T20:01:43","date_gmt":"2024-08-21T01:01:43","guid":{"rendered":"http:\/\/globalnewsmexico.com\/sitio\/?p=68480"},"modified":"2024-08-20T20:01:45","modified_gmt":"2024-08-21T01:01:45","slug":"acompana-presidenta-del-congreso-a-estudiantes-egresados-de-la-upav","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/acompana-presidenta-del-congreso-a-estudiantes-egresados-de-la-upav\/","title":{"rendered":"Acompa\u00f1a Presidenta del Congreso a estudiantes egresados de la UPAV"},"content":{"rendered":"\n<p>XALAPA, VER.- 16 DE AGOSTO DE 2024<\/p>\n\n\n\n<p>Recibe diputada Adriana Esther Mart\u00ednez S\u00e1nchez a la generaci\u00f3n 2021-2024 de la licenciatura en Ciencias Pol\u00edticas.<\/p>\n\n\n\n<p>Como profesionistas en Ciencias Pol\u00edticas tendr\u00e1n la oportunidad de aportar su capacidad y talento en la construcci\u00f3n de los destinos de Veracruz y M\u00e9xico en camino hacia el bienestar y progreso, afirm\u00f3 la presidenta de la Mesa Directiva de la LXVI Legislatura, diputada Adriana Esther Mart\u00ednez S\u00e1nchez, al atestiguar la ceremonia de graduaci\u00f3n de alumnos de la Universidad Popular Aut\u00f3noma de Veracruz (UPAV).<\/p>\n\n\n\n<p>En el auditorio Sebasti\u00e1n Lerdo de Tejada del Palacio Legislativo, luego de felicitar a los reci\u00e9n egresados de la generaci\u00f3n 2021-2024, la legisladora expres\u00f3 que los conocimientos adquiridos a lo largo de su carrera les permitir\u00e1 abrirse paso en la vida convirti\u00e9ndose en l\u00edderes en las diferentes \u00e1reas donde se desempe\u00f1en.<\/p>\n\n\n\n<p>Asimismo, reconoci\u00f3 el esfuerzo de la comunidad docente y administrativa de la UPAV, por el compromiso con la sociedad para forjar nuevos profesionales con vocaci\u00f3n de servicio que respondan a las necesidades de Veracruz.<\/p>\n\n\n\n<p>Al acto asistieron, por la UPAV, el director y fundador de la licenciatura de Ciencias Pol\u00edticas, Lenin Torres Antonio; la coordinadora y docente Astrid Lisette Gonz\u00e1lez Romero, y \u00c1ngel Rafael Mart\u00ednez Alarc\u00f3n, docente y fundador de la universidad; por parte del Ayuntamiento de Xalapa, Erik C\u00f3rdoba del Valle; en representaci\u00f3n de la Secretar\u00eda de Agricultura y Desarrollo Rural (Sader), Pedro Hussein Lases Mendoza, as\u00ed como personal directivo y administrativo de dicha casa de estudios.<\/p>\n\n\n\n<p>Fuente:: Redacci\u00f3n<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XALAPA, VER.- 16 DE AGOSTO DE 2024 Recibe diputada Adriana Esther Mart\u00ednez S\u00e1nchez a la generaci\u00f3n 2021-2024 de la licenciatura en Ciencias Pol\u00edticas. Como profesionistas en Ciencias Pol\u00edticas tendr\u00e1n la oportunidad de aportar su capacidad y talento en la construcci\u00f3n de los destinos de Veracruz y M\u00e9xico en camino hacia el bienestar y progreso, afirm\u00f3<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/acompana-presidenta-del-congreso-a-estudiantes-egresados-de-la-upav\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":5,"featured_media":68481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[37,8,50,52],"tags":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2024\/08\/16-de-agosto.jpg?fit=1359%2C818&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-hOw","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/68480"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=68480"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/68480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/68481"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=68480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=68480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=68480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}