{"id":69597,"date":"2025-09-01T20:29:53","date_gmt":"2025-09-02T01:29:53","guid":{"rendered":"https:\/\/globalnewsmexico.com\/sitio\/?p=69597"},"modified":"2025-09-01T20:29:54","modified_gmt":"2025-09-02T01:29:54","slug":"atrae-gobierno-de-delfina-gomez-proyectos-de-inversion-por-mas-de-mil-500-millones-de-pesos-para-el-edomex","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/atrae-gobierno-de-delfina-gomez-proyectos-de-inversion-por-mas-de-mil-500-millones-de-pesos-para-el-edomex\/","title":{"rendered":"Atrae Gobierno de Delfina G\u00f3mez proyectos de inversi\u00f3n por m\u00e1s de mil 500 millones de pesos para el EdoM\u00e9x"},"content":{"rendered":"\n<ul>\n<li>Se generar\u00e1n m\u00e1s de mil empleos en sectores como farmac\u00e9utico, de alimentos, papelero y de comercio.<\/li>\n<\/ul>\n\n\n\n<p>TOLUCA, Estado de M\u00e9xico.- A casi dos a\u00f1os de la administraci\u00f3n de la Gobernadora Delfina G\u00f3mez \u00c1lvarez, el Estado de M\u00e9xico contin\u00faa consolid\u00e1ndose como un destino atractivo para los empresarios, muestra de ello, es la suma de m\u00e1s de mil 500 millones de pesos que se han registrado recientemente en proyectos de sectores farmac\u00e9utico, de alimentos, papelero y de comercio, que emplear\u00e1n a m\u00e1s de mil mexiquenses.<\/p>\n\n\n\n<p>Estas inversiones representan un paso firme en este Gobierno y est\u00e1n orientadas a abrir nuevas oportunidades de desarrollo, impulsar la competitividad y generar nuevos empleos, pensando siempre en el beneficio de las y los mexiquenses.<\/p>\n\n\n\n<p>As\u00ed lo destac\u00f3 la titular de la Secretar\u00eda de Desarrollo Econ\u00f3mico, Laura Gonz\u00e1lez Hern\u00e1ndez, quien record\u00f3 que en lo que va de esta administraci\u00f3n se han registrado 140 mil 155 millones de pesos de inversi\u00f3n nacional y m\u00e1s de 138 mil empleos formales.<\/p>\n\n\n\n<p>Dentro de estas inversiones, Sigma Alimentos empresa multinacional dedicada a alimentos refrigerados, expandir\u00e1 y mejorar\u00e1 la infraestructura de sus plantas ubicadas en los municipios de Ecatepec, Nezahualc\u00f3yotl, La Paz y Tepotzotl\u00e1n, con un monto de 336 millones de pesos y la generaci\u00f3n de 300 nuevos empleos.<\/p>\n\n\n\n<p>Grupo SOMAR, compa\u00f1\u00eda dedicada al desarrollo, fabricaci\u00f3n y comercializaci\u00f3n de productos farmac\u00e9uticos, invertir\u00e1 202 millones de pesos para aumentar su producci\u00f3n de efervescentes y medicamentos s\u00f3lidos orales en su planta de Chalco, adem\u00e1s de dar mantenimiento e instalar una nueva l\u00ednea de c\u00e1psulas de gel en su planta de Naucalpan, con lo que emplear\u00e1n a 260 mexiquenses.<\/p>\n\n\n\n<p>Por su parte, Grupo Corporativo Papelera fabricante de art\u00edculos higi\u00e9nicos de papel, anunci\u00f3 que expandir\u00e1n las operaciones de sus plantas ubicadas en los municipios de Huehuetoca y Tepetlaoxtoc, con una inversi\u00f3n de m\u00e1s de 800 millones de pesos y la generaci\u00f3n de m\u00e1s de 225 nuevos empleos.<\/p>\n\n\n\n<p>La cadena comercial Tiendas Neto, anunci\u00f3 tambi\u00e9n una inversi\u00f3n de 210 millones de pesos para la apertura de 55 nuevos puntos de venta en diversos municipios mexiquenses y la generaci\u00f3n de m\u00e1s de 400 empleos en el sector comercio.<\/p>\n\n\n\n<p>Estos anuncios se han logrado gracias al acompa\u00f1amiento permanente que se le ha dado al sector empresarial, el respaldo a sus proyectos y a las acciones que se han puesto en marcha para generar las condiciones que permitan no solo cuidar los proyectos que ya se tienen, sino atraer nuevos, y as\u00ed seguir generando una econom\u00eda s\u00f3lida en beneficio de las familias mexiquenses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOLUCA, Estado de M\u00e9xico.- A casi dos a\u00f1os de la administraci\u00f3n de la Gobernadora Delfina G\u00f3mez \u00c1lvarez, el Estado de M\u00e9xico contin\u00faa consolid\u00e1ndose como un destino atractivo para los empresarios, muestra de ello, es la suma de m\u00e1s de mil 500 millones de pesos que se han registrado recientemente en proyectos de sectores farmac\u00e9utico, de<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/atrae-gobierno-de-delfina-gomez-proyectos-de-inversion-por-mas-de-mil-500-millones-de-pesos-para-el-edomex\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":13,"featured_media":69598,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[208],"tags":[295,211,214,298,299,209],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-24.jpg?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-i6x","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/69597"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=69597"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/69597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/69598"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=69597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=69597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=69597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}