{"id":69931,"date":"2025-10-16T16:55:13","date_gmt":"2025-10-16T21:55:13","guid":{"rendered":"https:\/\/globalnewsmexico.com\/sitio\/?p=69931"},"modified":"2025-10-16T16:55:14","modified_gmt":"2025-10-16T21:55:14","slug":"gobernadora-delfina-gomez-y-olimpia-coral-impulsan-campana-contra-la-violencia-digital-en-el-edomex","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/gobernadora-delfina-gomez-y-olimpia-coral-impulsan-campana-contra-la-violencia-digital-en-el-edomex\/","title":{"rendered":"Gobernadora Delfina G\u00f3mez y Olimpia Coral impulsan campa\u00f1a contra la violencia digital en el Edomex"},"content":{"rendered":"\n<p><strong>TLALNEPANTLA, Estado de M\u00e9xico.<\/strong> Este 16 de octubre de 2025 se present\u00f3 la campa\u00f1a <strong>\u201cEn Redes, No Te Enredes\u201d<\/strong>, encabezada por la gobernadora Delfina G\u00f3mez \u00c1lvarez y la activista Olimpia Coral Melo. El objetivo central es prevenir la violencia digital, fomentar el uso responsable de internet y sensibilizar a ni\u00f1as, ni\u00f1os y adolescentes sobre los riesgos y comportamientos nocivos en entornos digitales. La Secretar\u00eda de las Mujeres (SeMujeres) y la Secretar\u00eda de Educaci\u00f3n, Ciencia, Tecnolog\u00eda e Innovaci\u00f3n (SECTI) colaborar\u00e1n para implementar una \u201cGu\u00eda pr\u00e1ctica para la prevenci\u00f3n y detecci\u00f3n de la violencia en espacios escolares\u201d.<\/p>\n\n\n\n<p>La gobernadora enfatiz\u00f3 que, frente al aumento del uso de internet \u2014que en M\u00e9xico alcanza a m\u00e1s del 83\u202f% de la poblaci\u00f3n mayor de seis a\u00f1os, seg\u00fan datos del INEGI\u2014, es urgente crear \u201centornos digitales libres de violencia\u201d mediante estrategias de educaci\u00f3n digital, denuncia y atenci\u00f3n. Adem\u00e1s, record\u00f3 que en el Estado de M\u00e9xico ya se aplica la Ley Olimpia, la cual sanciona la difusi\u00f3n de contenido sexual sin consentimiento, protegiendo la privacidad y dignidad de las personas. Durante la presentaci\u00f3n estuvo presente tambi\u00e9n la secretaria M\u00f3nica Ch\u00e1vez Dur\u00e1n, quien alert\u00f3 que m\u00e1s de la mitad de las mujeres de 12 a\u00f1os o m\u00e1s han sufrido ciberacoso, y seis de cada diez menores han interactuado con desconocidos en redes o videojuegos.<\/p>\n\n\n\n<p>La titular de SeMujeres explic\u00f3 que la \u201cGu\u00eda pr\u00e1ctica\u201d buscar\u00e1 dotar a docentes y autoridades educativas de herramientas para identificar riesgos digitales en los entornos escolares y actuar oportunamente. La campa\u00f1a se construye en alianza con especialistas, colectivos y defensoras digitales, encabezados por Olimpia Coral Melo, cuya trayectoria en la lucha contra la violencia digital fue reconocida durante el evento. En el cierre, Melo ofreci\u00f3 una conferencia magistral, acompa\u00f1ada por autoridades estatales y municipales.<\/p>\n\n\n\n<p>La campa\u00f1a \u201cEn Redes, No Te Enredes\u201d representa un paso significativo en la pol\u00edtica p\u00fablica del Edomex para enfrentar los retos de la ciberviolencia, sobre todo en j\u00f3venes y mujeres. Su implementaci\u00f3n colaborativa con el sector educativo refuerza el compromiso estatal de prevenir, atender y sancionar agresiones digitales, construyendo espacios escolares y digitales m\u00e1s seguros para todas y todos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TLALNEPANTLA, Estado de M\u00e9xico. Este 16 de octubre de 2025 se present\u00f3 la campa\u00f1a \u201cEn Redes, No Te Enredes\u201d, encabezada por la gobernadora Delfina G\u00f3mez \u00c1lvarez y la activista Olimpia Coral Melo. El objetivo central es prevenir la violencia digital, fomentar el uso responsable de internet y sensibilizar a ni\u00f1as, ni\u00f1os y adolescentes sobre los<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/gobernadora-delfina-gomez-y-olimpia-coral-impulsan-campana-contra-la-violencia-digital-en-el-edomex\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":12,"featured_media":69932,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[208],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2025\/10\/Agilizara-Toluca-tramites-de-divorcio-para-personas-violentadas-40.png?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-ibV","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/69931"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=69931"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/69931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/69932"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=69931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=69931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=69931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}