{"id":69942,"date":"2025-10-17T15:03:10","date_gmt":"2025-10-17T20:03:10","guid":{"rendered":"https:\/\/globalnewsmexico.com\/sitio\/?p=69942"},"modified":"2025-10-17T15:03:11","modified_gmt":"2025-10-17T20:03:11","slug":"personas-con-discapacidad-celebran-viaje-con-sentidos-en-el-insurgente-rumbo-a-una-inclusion-real","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/personas-con-discapacidad-celebran-viaje-con-sentidos-en-el-insurgente-rumbo-a-una-inclusion-real\/","title":{"rendered":"Personas con discapacidad celebran \u201cViaje con sentidos\u201d en El Insurgente rumbo a una inclusi\u00f3n real"},"content":{"rendered":"\n<p><strong>Toluca, Estado de M\u00e9xico<\/strong> \u2014 En conmemoraci\u00f3n del D\u00eda Mundial del Bast\u00f3n Blanco, el DIFEM organiz\u00f3 el \u201cViaje con sentidos\u201d en el tren interurbano El Insurgente, con la participaci\u00f3n de 180 personas con discapacidad visual. La actividad sensorial busca sensibilizar sobre la autonom\u00eda, accesibilidad y respeto en espacios p\u00fablicos de movilidad.<\/p>\n\n\n\n<p>Durante el trayecto, se formaron tr\u00edos compuestos por una persona con discapacidad visual, otra con los ojos vendados y una tercera como gu\u00eda, para orientar en el uso del bast\u00f3n blanco, gu\u00edas podot\u00e1ctiles y orientarse en estaciones, taquillas, zonas de riesgo y sanitarios. En ese evento, se entregaron bastones y se impartieron pl\u00e1ticas de sensibilizaci\u00f3n. Este ejercicio conjunto involucr\u00f3 a los Sistemas DIF municipales, asociaciones civiles, operadores del transporte y servidores p\u00fablicos.<\/p>\n\n\n\n<p>El Insurgente ya contempla elementos de accesibilidad para personas con discapacidad visual, como cintas podot\u00e1ctiles y estaciones con se\u00f1alizaci\u00f3n para solicitar apoyo al personal del tren. No obstante, usuarios han denunciado que algunas estaciones del tren han carecido de infraestructura adecuada \u2014por ejemplo, escaleras el\u00e9ctricas o elevadores que no operan\u2014 lo que limita la movilidad segura para quienes usan bast\u00f3n, muletas o silla de ruedas. Este contraste resalta la necesidad de que estos eventos sean acompa\u00f1ados de mejoras estructurales permanentes.<\/p>\n\n\n\n<p>La titular del DIFEM, Karina Labastida Sotelo, subraya que acciones como esta fortalecen los procesos de inclusi\u00f3n y fomentan entornos m\u00e1s sensibles y accesibles para todas las personas. El programa de gobierno incluye la entrega de ayudas t\u00e9cnicas \u2014bastones, sillas de ruedas, andaderas\u2014 y el dise\u00f1o de escenarios de convivencia que atiendan la diversidad funcional.<\/p>\n\n\n\n<p><strong>Cierre<\/strong><br>El \u201cViaje con sentidos\u201d no solo busca sensibilizar, sino construir puentes tangibles hacia una movilidad interurbana m\u00e1s humana, emp\u00e1tica e incluyente, donde las personas con discapacidad visual puedan transitar con dignidad y autonom\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toluca, Estado de M\u00e9xico \u2014 En conmemoraci\u00f3n del D\u00eda Mundial del Bast\u00f3n Blanco, el DIFEM organiz\u00f3 el \u201cViaje con sentidos\u201d en el tren interurbano El Insurgente, con la participaci\u00f3n de 180 personas con discapacidad visual. La actividad sensorial busca sensibilizar sobre la autonom\u00eda, accesibilidad y respeto en espacios p\u00fablicos de movilidad. Durante el trayecto, se<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/personas-con-discapacidad-celebran-viaje-con-sentidos-en-el-insurgente-rumbo-a-una-inclusion-real\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":12,"featured_media":69943,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[208],"tags":[],"jetpack_featured_media_url":"https:\/\/i2.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2025\/10\/Agilizara-Toluca-tramites-de-divorcio-para-personas-violentadas-45.png?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-ic6","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/69942"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=69942"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/69942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/69943"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=69942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=69942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=69942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}