{"id":70022,"date":"2025-10-27T14:03:39","date_gmt":"2025-10-27T20:03:39","guid":{"rendered":"https:\/\/globalnewsmexico.com\/sitio\/?p=70022"},"modified":"2025-10-27T14:03:40","modified_gmt":"2025-10-27T20:03:40","slug":"edomex-preve-casi-2-mil-millones-de-pesos-por-venta-de-flor-de-cempasuchil-en-dia-de-muertos","status":"publish","type":"post","link":"https:\/\/globalnewsmexico.com\/sitio\/edomex-preve-casi-2-mil-millones-de-pesos-por-venta-de-flor-de-cempasuchil-en-dia-de-muertos\/","title":{"rendered":"EdoM\u00e9x prev\u00e9 casi 2 mil millones de pesos por venta de flor de cempas\u00fachil en D\u00eda de Muertos"},"content":{"rendered":"\n<p><strong>Metepec, Estado de M\u00e9xico.<\/strong> \u2013 La venta de flor de cempas\u00fachil en la temporada del D\u00eda de Muertos podr\u00eda generar una derrama econ\u00f3mica de <strong>1,991 millones de pesos<\/strong> en el Estado de M\u00e9xico, inform\u00f3 la Secretar\u00eda del Campo. La entidad se mantiene como uno de los principales productores del pa\u00eds, ocupando el <strong>tercer lugar nacional<\/strong> en esta flor, s\u00f3lo detr\u00e1s de Puebla y la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p>El gobierno estatal, a trav\u00e9s del <strong>Programa Transformando el Campo<\/strong>, otorga apoyos directos a los floricultores para fortalecer la producci\u00f3n, infraestructura y comercializaci\u00f3n. Estos incentivos incluyen insumos agr\u00edcolas como cubierta pl\u00e1stica y material vegetativo, as\u00ed como equipamiento como invernaderos y sistemas de riego tecnificado, con el objetivo de impulsar la productividad y competitividad del sector.<\/p>\n\n\n\n<p>Actualmente, la flor de cempas\u00fachil se cultiva en <strong>1,937 hect\u00e1reas<\/strong> en municipios como Atlacomulco, Tenango del Valle, Texcoco, Chicoloapan, Ozumba, Tenancingo, Tepetlixpa, Malinalco y Chimalhuac\u00e1n. Esta flor, considerada un <strong>patrimonio cultural<\/strong>, forma parte esencial de las ofrendas de D\u00eda de Muertos, guiando simb\u00f3licamente a las almas hacia los altares familiares.<\/p>\n\n\n\n<p>El Estado de M\u00e9xico tambi\u00e9n lidera la producci\u00f3n de <strong>flor de corte<\/strong>, con m\u00e1s de <strong>7,172 hect\u00e1reas cultivadas<\/strong> y un valor de producci\u00f3n superior a los <strong>7,883 millones de pesos<\/strong>, consolidando su posici\u00f3n como referente nacional en floricultura.<\/p>\n\n\n\n<p>Con estas acciones, el Gobierno mexiquense reafirma su compromiso de apoyar a los floricultores, promoviendo una actividad <strong>productiva, sostenible y de orgullo<\/strong> para las comunidades rurales de la entidad.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Metepec, Estado de M\u00e9xico. \u2013 La venta de flor de cempas\u00fachil en la temporada del D\u00eda de Muertos podr\u00eda generar una derrama econ\u00f3mica de 1,991 millones de pesos en el Estado de M\u00e9xico, inform\u00f3 la Secretar\u00eda del Campo. La entidad se mantiene como uno de los principales productores del pa\u00eds, ocupando el tercer lugar nacional<a class=\"read-more\" href=\"https:\/\/globalnewsmexico.com\/sitio\/edomex-preve-casi-2-mil-millones-de-pesos-por-venta-de-flor-de-cempasuchil-en-dia-de-muertos\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":12,"featured_media":70023,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","footnotes":""},"categories":[208],"tags":[],"jetpack_featured_media_url":"https:\/\/i1.wp.com\/globalnewsmexico.com\/sitio\/wp-content\/uploads\/2025\/10\/Agilizara-Toluca-tramites-de-divorcio-para-personas-violentadas-64.png?fit=1920%2C1080&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9yqPL-ido","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/70022"}],"collection":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/comments?post=70022"}],"version-history":[{"count":0,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/posts\/70022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media\/70023"}],"wp:attachment":[{"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/media?parent=70022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/categories?post=70022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/globalnewsmexico.com\/sitio\/wp-json\/wp\/v2\/tags?post=70022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}